{"id":32791,"date":"2024-03-26T08:32:10","date_gmt":"2024-03-26T08:32:10","guid":{"rendered":"https:\/\/klang.io\/help\/songbook\/"},"modified":"2025-12-01T06:19:28","modified_gmt":"2025-12-01T06:19:28","password":"","slug":"songbook","status":"publish","type":"docs","link":"https:\/\/klang.io\/es\/help\/songbook\/","title":{"rendered":"C\u00f3mo usar el cancionero de Klangio"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Si busca una forma de organizar <a href=\"\/?knowledge_base=what-music-transcribe\" target=\"_blank\" rel=\"noreferrer noopener\">sus transcripciones musicales de sus aplicaciones de Klangio<\/a>, entonces el cancionero es exactamente lo que est\u00e1 buscando. En esta gu\u00eda, le mostrar\u00e9 c\u00f3mo usar el cancionero de Klangio y le explicar\u00e9 todas las funciones que incluye.<\/p>\n\n<p class=\"wp-block-paragraph\">Contin\u00fae leyendo o vea el video de YouTube:<\/p>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Using your Klangio Songbook | The Ultimate Guide to Klangio\" width=\"800\" height=\"450\" data-src=\"https:\/\/www.youtube.com\/embed\/p0Ai6H-3xrs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe>\n<\/div><\/figure>\n\n<h2 class=\"wp-block-heading\">Abrir el cancionero<\/h2>\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"396\" src=\"\/wp-content\/uploads\/2024\/04\/grafik-1024x396.png\" alt=\"La pantalla de inicio de sesi&#xF3;n del sitio web de Klangio\" class=\"wp-image-17435\" style=\"width:654px;height:auto\" srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-1024x396.png 1024w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-300x116.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-768x297.png 768w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-360x139.png 360w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik.png 1527w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Inicie sesi\u00f3n en su cuenta de Klangio y seleccione su aplicaci\u00f3n<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Para acceder al cancionero, primero deber\u00e1 <a href=\"\/?knowledge_base=create-account\" target=\"_blank\" rel=\"noreferrer noopener\">iniciar sesi\u00f3n en su cuenta<\/a> y abrir la aplicaci\u00f3n de Klangio para la que desea ver el cancionero.<\/p>\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img decoding=\"async\" width=\"1024\" height=\"359\" data-src=\"\/wp-content\/uploads\/2024\/04\/grafik-1-1024x359.png\" alt=\"El sitio web de Piano2Notes, que muestra el bot&#xF3;n Cancionero\" class=\"wp-image-17440 lazyload\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/359;width:652px;height:auto\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-1-1024x359.png 1024w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-1-300x105.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-1-768x269.png 768w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-1-360x126.png 360w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-1.png 1237w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">Haga clic en \u201cMI CANCIONERO\u201d en la parte superior de la pantalla<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Luego, en la esquina superior derecha, encontrar\u00e1 un bot\u00f3n etiquetado con \u201cMI CANCIONERO\u201d que abre el cancionero.<\/p>\n\n<p class=\"wp-block-paragraph\">Ahora echemos un vistazo a todas las caracter\u00edsticas del cancionero:<\/p>\n\n<h2 class=\"wp-block-heading\">Comenzar una transcripci\u00f3n en el cancionero<\/h2>\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"89\" data-src=\"\/wp-content\/uploads\/2024\/04\/grafik-2-1024x89.png\" alt=\"El cancionero de Piano2Notes, que te permite comenzar una nueva Klangio Transcription\" class=\"wp-image-17445 lazyload\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-2-1024x89.png 1024w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-2-300x26.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-2-768x67.png 768w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-2-1536x134.png 1536w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-2-360x31.png 360w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-2.png 1632w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/89;\" \/><figcaption class=\"wp-element-caption\">Pegue un enlace de YouTube o arrastre y suelte un archivo de audio en el cuadro para comenzar una nueva transcripci\u00f3n.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">En la parte superior, tiene la opci\u00f3n de <a href=\"\/?knowledge_base=audio-youtube-into-sheet\" target=\"_blank\" rel=\"noreferrer noopener\">comenzar una nueva transcripci\u00f3n<\/a>, arrastrando y soltando un archivo de audio o pegando un enlace de YouTube.<\/p>\n\n<h2 class=\"wp-block-heading\">Encuentre y abra sus transcripciones anteriores<\/h2>\n\n<figure class=\"wp-block-image aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"160\" data-src=\"\/wp-content\/uploads\/2024\/04\/grafik-3-1024x160.png\" alt=\"El cancionero de Piano2Notes, que le permite encontrar y abrir sus transcripciones anteriores\" class=\"wp-image-17450 lazyload\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-3-1024x160.png 1024w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-3-300x47.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-3-768x120.png 768w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-3-1536x240.png 1536w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-3-360x56.png 360w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-3.png 1827w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/160;\" \/><figcaption class=\"wp-element-caption\">Utilice la secci\u00f3n principal para encontrar sus transcripciones anteriores.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">La secci\u00f3n principal del cancionero le permite acceder a sus transcripciones anteriores. Simplemente despl\u00e1cese por sus canciones o use la barra de b\u00fasqueda de arriba para encontrar una determinada transcripci\u00f3n. Haga clic en el t\u00edtulo para abrir la pieza en el <a href=\"\/?knowledge_base=transcription-viewer\" target=\"_blank\" rel=\"noreferrer noopener\">visor de transcripciones<\/a>.  <\/p>\n\n<h3 class=\"wp-block-heading\">\u00bfHan desaparecido tus canciones?<\/h3>\n\n<p class=\"wp-block-paragraph\">Normalmente, esto se debe a una de estas causas:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Tu transcripci\u00f3n gratuita ha caducado. Esto ocurre despu\u00e9s de 30 d\u00edas cuando has realizado una transcripci\u00f3n de demostraci\u00f3n gratuita y no has iniciado sesi\u00f3n en una cuenta para reclamarla. <\/li>\n\n\n\n<li>Ha reclamado la transcripci\u00f3n con una cuenta, pero no ha iniciado sesi\u00f3n en esa cuenta. Aseg\u00farese de comprobar si ha iniciado sesi\u00f3n en una cuenta diferente por accidente. Compruebe sus diferentes correos electr\u00f3nicos y las opciones de inicio de sesi\u00f3n de Google \/ Apple.  <\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Si a\u00fan no puedes encontrar tus transcripciones, por favor, abre nuestro chatbot (el bot\u00f3n &#8220;Support&#8221; en el lado derecho de tu pantalla) y pide hablar con uno de los miembros de nuestro equipo de soporte. \u00a1Estaremos encantados de ayudarte! <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\">El men\u00fa de acciones<\/h2>\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" width=\"201\" height=\"92\" data-src=\"\/wp-content\/uploads\/2024\/04\/grafik-4.png\" alt=\"Las acciones disponibles en el cancionero de las aplicaciones de Klangio.\" class=\"wp-image-17455 lazyload\" style=\"--smush-placeholder-width: 201px; --smush-placeholder-aspect-ratio: 201\/92;width:374px;height:auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">Pase el cursor sobre la columna Acciones de una canci\u00f3n para ver los iconos de acci\u00f3n.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Es posible que haya notado que hay una columna llamada \u201cAcciones\u201d en su historial de transcripciones. Al pasar el cursor sobre esta secci\u00f3n, aparecer\u00e1n diferentes acciones: <\/p>\n\n<ul class=\"wp-block-list\">\n<li><a href=\"\/?knowledge_base=refund-a-transcription\" target=\"_blank\" rel=\"noreferrer noopener\">Reembolso<\/a>: Haga clic aqu\u00ed para recuperar su ticket de transcripci\u00f3n si hizo una transcripci\u00f3n completa.<\/li>\n\n\n\n<li><a href=\"\/?knowledge_base=download-formats\" target=\"_blank\" rel=\"noreferrer noopener\">Descargar<\/a>: Haga clic aqu\u00ed para descargar diferentes formatos de transcripci\u00f3n<\/li>\n\n\n\n<li>Editar t\u00edtulo: Cambiar el t\u00edtulo y el compositor de la transcripci\u00f3n<\/li>\n\n\n\n<li>Eliminar: Eliminar permanentemente una transcripci\u00f3n<\/li>\n\n\n\n<li><a href=\"\/?knowledge_base=retranscribe\" target=\"_blank\" rel=\"noreferrer noopener\">Volver a transcribir<\/a>: Cambiar la <a href=\"\/?knowledge_base=additional-information\" target=\"_blank\" rel=\"noreferrer noopener\">Configuraci\u00f3n adicional<\/a> de una transcripci\u00f3n rehaciendo la transcripci\u00f3n (de forma gratuita)<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\">El cancionero de las aplicaciones m\u00f3viles de Klangio<\/h2>\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img decoding=\"async\" width=\"493\" height=\"1024\" data-src=\"\/wp-content\/uploads\/2024\/04\/grafik-5-493x1024.png\" alt=\"El cancionero de las aplicaciones m&#xF3;viles de Klangio, que permite acceder a todas las canciones transcritas anteriormente.\" class=\"wp-image-17460 lazyload\" style=\"--smush-placeholder-width: 493px; --smush-placeholder-aspect-ratio: 493\/1024;width:273px;height:auto\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-5-493x1024.png 493w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-5-144x300.png 144w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-5-768x1596.png 768w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-5-739x1536.png 739w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-5-246x512.png 246w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-5.png 940w\" data-sizes=\"(max-width: 493px) 100vw, 493px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">El cancionero de las aplicaciones m\u00f3viles de Klangio<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Por supuesto, el cancionero tambi\u00e9n est\u00e1 disponible en las <a href=\"\/?knowledge_base=download-klangio-apps\" target=\"_blank\" rel=\"noreferrer noopener\">aplicaciones m\u00f3viles de Klangio<\/a>, lo que le permite acceder a sus canciones transcritas en cualquiera de sus dispositivos. Aseg\u00farese de <a href=\"\/?knowledge_base=create-account\" target=\"_blank\" rel=\"noreferrer noopener\">usar la misma cuenta de Klangio<\/a> al hacerlo.<\/p>\n\n<p class=\"wp-block-paragraph\">Se le presentar\u00e1 el cancionero directamente al abrir la aplicaci\u00f3n.<\/p>\n\n<p class=\"wp-block-paragraph\">No dude en consultar los otros art\u00edculos de nuestro <a href=\"https:\/\/klang.io\/help\" target=\"_blank\" rel=\"noreferrer noopener\">Centro de Ayuda<\/a>, si tiene preguntas sobre c\u00f3mo usar el cancionero de Klangio.<\/p>\n\n<h2 class=\"wp-block-heading\">Preguntas frecuentes<\/h2>\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1764079973187\"><strong class=\"schema-faq-question\">\u00bfPuedo ordenar mis canciones en mi cancionero?<\/strong> <p class=\"schema-faq-answer\">\u00a1S\u00ed! Puede ordenar sus canciones por nombre o fecha. Simplemente haga clic en el icono a la derecha de la barra de b\u00fasqueda. <\/p> <\/div> <\/div>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si busca una forma de organizar sus transcripciones musicales de sus aplicaciones de Klangio, entonces el cancionero es exactamente lo que est\u00e1 buscando. En esta gu\u00eda, le mostrar\u00e9 c\u00f3mo usar el cancionero de Klangio y le explicar\u00e9 todas las funciones que incluye. Contin\u00fae leyendo o vea el video de YouTube: Abrir el cancionero Para acceder [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":17469,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"doc_category":[513],"doc_tag":[],"knowledge_base":[443,441,444,440,445,442],"class_list":["post-32791","docs","type-docs","status-publish","has-post-thumbnail","hentry","doc_category-songbook-es","knowledge_base-drum2notes","knowledge_base-guitar2tabs","knowledge_base-klangio-transcription-studio","knowledge_base-piano2notes","knowledge_base-scan2notes","knowledge_base-sing2notes"],"year_month":"2026-07","word_count":644,"total_views":"502","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"Christoph Zimmer","author_nicename":"chris","author_url":"https:\/\/klang.io\/es\/blog\/author\/chris\/"},"doc_category_info":[{"term_name":"Songbook","term_url":"https:\/\/klang.io\/es\/help\/non-knowledgebase\/songbook-es\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00f3mo usar el cancionero de Klangio | klang.io<\/title>\n<meta name=\"description\" content=\"Aprenda a usar el cancionero de Klangio. Encuentre y abra todas sus transcripciones anteriores y acceda a muchas funciones en el men\u00fa Acci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/klang.io\/es\/help\/songbook\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo usar el cancionero de Klangio | klang.io\" \/>\n<meta property=\"og:description\" content=\"Aprenda a usar el cancionero de Klangio. Encuentre y abra todas sus transcripciones anteriores y acceda a muchas funciones en el men\u00fa Acci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/klang.io\/es\/help\/songbook\/\" \/>\n<meta property=\"og:site_name\" content=\"klang.io\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/klangio\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-01T06:19:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/songbook.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@klangio\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\/\/klang.io\/es\/help\/songbook\/\",\"url\":\"https:\/\/klang.io\/es\/help\/songbook\/\",\"name\":\"C\u00f3mo usar el cancionero de Klangio | klang.io\",\"isPartOf\":{\"@id\":\"https:\/\/klang.io\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/klang.io\/es\/help\/songbook\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/klang.io\/es\/help\/songbook\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/songbook.png\",\"datePublished\":\"2024-03-26T08:32:10+00:00\",\"dateModified\":\"2025-12-01T06:19:28+00:00\",\"description\":\"Aprenda a usar el cancionero de Klangio. Encuentre y abra todas sus transcripciones anteriores y acceda a muchas funciones en el men\u00fa Acci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\/\/klang.io\/es\/help\/songbook\/#breadcrumb\"},\"mainEntity\":[{\"@id\":\"https:\/\/klang.io\/es\/help\/songbook\/#faq-question-1764079973187\"}],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/klang.io\/es\/help\/songbook\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/klang.io\/es\/help\/songbook\/#primaryimage\",\"url\":\"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/songbook.png\",\"contentUrl\":\"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/songbook.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/klang.io\/es\/help\/songbook\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/klang.io\/es\/home-2\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Help Center\",\"item\":\"https:\/\/klang.io\/es\/help\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C\u00f3mo usar el cancionero de Klangio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/klang.io\/es\/#website\",\"url\":\"https:\/\/klang.io\/es\/\",\"name\":\"Klangio\",\"description\":\"AI Tools for Musicians\",\"publisher\":{\"@id\":\"https:\/\/klang.io\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/klang.io\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/klang.io\/es\/#organization\",\"name\":\"Klangio GmbH\",\"url\":\"https:\/\/klang.io\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/klang.io\/es\/#\/schema\/logo\/image\/\",\"url\":\"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png\",\"contentUrl\":\"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png\",\"width\":512,\"height\":512,\"caption\":\"Klangio GmbH\"},\"image\":{\"@id\":\"https:\/\/klang.io\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/klangio\",\"https:\/\/x.com\/klangio\",\"https:\/\/www.linkedin.com\/company\/klangio\/\",\"https:\/\/www.instagram.com\/klangio\/\",\"https:\/\/www.youtube.com\/@Klangio\"]},{\"@type\":\"Question\",\"@id\":\"https:\/\/klang.io\/es\/help\/songbook\/#faq-question-1764079973187\",\"position\":1,\"url\":\"https:\/\/klang.io\/es\/help\/songbook\/#faq-question-1764079973187\",\"name\":\"\u00bfPuedo ordenar mis canciones en mi cancionero?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"\u00a1S\u00ed! Puede ordenar sus canciones por nombre o fecha. Simplemente haga clic en el icono a la derecha de la barra de b\u00fasqueda. \",\"inLanguage\":\"es\"},\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo usar el cancionero de Klangio | klang.io","description":"Aprenda a usar el cancionero de Klangio. Encuentre y abra todas sus transcripciones anteriores y acceda a muchas funciones en el men\u00fa Acci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/klang.io\/es\/help\/songbook\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo usar el cancionero de Klangio | klang.io","og_description":"Aprenda a usar el cancionero de Klangio. Encuentre y abra todas sus transcripciones anteriores y acceda a muchas funciones en el men\u00fa Acci\u00f3n.","og_url":"https:\/\/klang.io\/es\/help\/songbook\/","og_site_name":"klang.io","article_publisher":"https:\/\/facebook.com\/klangio","article_modified_time":"2025-12-01T06:19:28+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/songbook.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@klangio","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","FAQPage"],"@id":"https:\/\/klang.io\/es\/help\/songbook\/","url":"https:\/\/klang.io\/es\/help\/songbook\/","name":"C\u00f3mo usar el cancionero de Klangio | klang.io","isPartOf":{"@id":"https:\/\/klang.io\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/klang.io\/es\/help\/songbook\/#primaryimage"},"image":{"@id":"https:\/\/klang.io\/es\/help\/songbook\/#primaryimage"},"thumbnailUrl":"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/songbook.png","datePublished":"2024-03-26T08:32:10+00:00","dateModified":"2025-12-01T06:19:28+00:00","description":"Aprenda a usar el cancionero de Klangio. Encuentre y abra todas sus transcripciones anteriores y acceda a muchas funciones en el men\u00fa Acci\u00f3n.","breadcrumb":{"@id":"https:\/\/klang.io\/es\/help\/songbook\/#breadcrumb"},"mainEntity":[{"@id":"https:\/\/klang.io\/es\/help\/songbook\/#faq-question-1764079973187"}],"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/klang.io\/es\/help\/songbook\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/klang.io\/es\/help\/songbook\/#primaryimage","url":"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/songbook.png","contentUrl":"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/songbook.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/klang.io\/es\/help\/songbook\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/klang.io\/es\/home-2\/"},{"@type":"ListItem","position":2,"name":"Help Center","item":"https:\/\/klang.io\/es\/help\/"},{"@type":"ListItem","position":3,"name":"C\u00f3mo usar el cancionero de Klangio"}]},{"@type":"WebSite","@id":"https:\/\/klang.io\/es\/#website","url":"https:\/\/klang.io\/es\/","name":"Klangio","description":"AI Tools for Musicians","publisher":{"@id":"https:\/\/klang.io\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/klang.io\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/klang.io\/es\/#organization","name":"Klangio GmbH","url":"https:\/\/klang.io\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/klang.io\/es\/#\/schema\/logo\/image\/","url":"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png","contentUrl":"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png","width":512,"height":512,"caption":"Klangio GmbH"},"image":{"@id":"https:\/\/klang.io\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/klangio","https:\/\/x.com\/klangio","https:\/\/www.linkedin.com\/company\/klangio\/","https:\/\/www.instagram.com\/klangio\/","https:\/\/www.youtube.com\/@Klangio"]},{"@type":"Question","@id":"https:\/\/klang.io\/es\/help\/songbook\/#faq-question-1764079973187","position":1,"url":"https:\/\/klang.io\/es\/help\/songbook\/#faq-question-1764079973187","name":"\u00bfPuedo ordenar mis canciones en mi cancionero?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"\u00a1S\u00ed! Puede ordenar sus canciones por nombre o fecha. Simplemente haga clic en el icono a la derecha de la barra de b\u00fasqueda. ","inLanguage":"es"},"inLanguage":"es"}]}},"knowledge_base_info":[{"term_name":"Drum2Notes","term_url":"https:\/\/klang.io\/es\/help\/drum2notes\/","term_slug":"drum2notes"},{"term_name":"Guitar2Tabs","term_url":"https:\/\/klang.io\/es\/help\/guitar2tabs\/","term_slug":"guitar2tabs"},{"term_name":"Klangio Transcription Studio","term_url":"https:\/\/klang.io\/es\/help\/klangio-transcription-studio\/","term_slug":"klangio-transcription-studio"},{"term_name":"Piano2Notes","term_url":"https:\/\/klang.io\/es\/help\/piano2notes\/","term_slug":"piano2notes"},{"term_name":"Scan2Notes","term_url":"https:\/\/klang.io\/es\/help\/scan2notes\/","term_slug":"scan2notes"},{"term_name":"Sing2Notes","term_url":"https:\/\/klang.io\/es\/help\/sing2notes\/","term_slug":"sing2notes"}],"knowledge_base_slug":["drum2notes","guitar2tabs","klangio-transcription-studio","piano2notes","scan2notes","sing2notes"],"_links":{"self":[{"href":"https:\/\/klang.io\/es\/wp-json\/wp\/v2\/docs\/32791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/klang.io\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/klang.io\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/klang.io\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/klang.io\/es\/wp-json\/wp\/v2\/comments?post=32791"}],"version-history":[{"count":3,"href":"https:\/\/klang.io\/es\/wp-json\/wp\/v2\/docs\/32791\/revisions"}],"predecessor-version":[{"id":41066,"href":"https:\/\/klang.io\/es\/wp-json\/wp\/v2\/docs\/32791\/revisions\/41066"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/klang.io\/es\/wp-json\/wp\/v2\/media\/17469"}],"wp:attachment":[{"href":"https:\/\/klang.io\/es\/wp-json\/wp\/v2\/media?parent=32791"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/klang.io\/es\/wp-json\/wp\/v2\/doc_category?post=32791"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/klang.io\/es\/wp-json\/wp\/v2\/doc_tag?post=32791"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/klang.io\/es\/wp-json\/wp\/v2\/knowledge_base?post=32791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}