{"id":32365,"date":"2024-04-24T09:48:41","date_gmt":"2024-04-24T09:48:41","guid":{"rendered":"https:\/\/klang.io\/help\/improve-quality\/"},"modified":"2025-10-23T09:51:24","modified_gmt":"2025-10-23T09:51:24","password":"","slug":"improve-quality","status":"publish","type":"docs","link":"https:\/\/klang.io\/fr\/help\/improve-quality\/","title":{"rendered":"Comment am\u00e9liorer la qualit\u00e9 de la transcription"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Si vous avez des difficult\u00e9s \u00e0 obtenir des notes utiles \u00e0 partir d&#8217;une transcription <a href=\"https:\/\/klang.io\/fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">Klangio<\/a>, alors cet article peut vous aider. Je vais vous montrer comment am\u00e9liorer la qualit\u00e9 de vos transcriptions.<\/p>\n\n<h2 class=\"wp-block-heading\">Limites des applications<\/h2>\n\n<p class=\"wp-block-paragraph\">Assurez-vous d&#8217;\u00eatre conscient des limites de chaque application. <a href=\"\/?knowledge_base=what-music-transcribe\" target=\"_blank\" rel=\"noreferrer noopener\">Vous pouvez en apprendre davantage ici<\/a>.<\/p>\n\n<h2 class=\"wp-block-heading\">Qualit\u00e9 de l&#8217;audio<\/h2>\n\n<p class=\"wp-block-paragraph\">Une bonne transcription ne peut r\u00e9sulter que d&#8217;un bon enregistrement. Cela signifie : <\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Utilisez un enregistrement propre :<\/strong> Les effets tels que la r\u00e9verb\u00e9ration, le d\u00e9lai et la distorsion auront un effet n\u00e9gatif sur la transcription. Notez qu&#8217;actuellement, pour les guitares \u00e9lectriques distordues, vous obtiendrez les meilleurs r\u00e9sultats en s\u00e9lectionnant &#8220;Guitare \u00e9lectrique&#8221;, puis &#8220;Instrument solo&#8221; et enfin &#8220;Picking&#8221; avec Guitar2Tabs ou Klangio Transcription Studio.<\/li>\n\n\n\n<li><strong>Microphone (lors de l&#8217;enregistrement personnel) :<\/strong> Apr\u00e8s l&#8217;enregistrement, r\u00e9\u00e9coutez pour vous assurer que la qualit\u00e9 audio est appropri\u00e9e. Klangio ne n\u00e9cessite pas d&#8217;\u00e9quipement d&#8217;enregistrement professionnel pour transcrire votre instrument \u2014 le microphone de votre smartphone suffira. Si vous transcrivez un morceau enregistr\u00e9 professionnellement et que les r\u00e9sultats sont inexacts, essayez d&#8217;utiliser le microphone de votre smartphone pour une meilleure pr\u00e9cision de transcription.  <\/li>\n\n\n\n<li><strong>Tempo constant<\/strong> : Si la musique alterne entre diff\u00e9rents tempos, il sera difficile de d\u00e9terminer la dur\u00e9e exacte des notes dans la partition. Si vous visez \u00e0 exporter un <a href=\"\/?knowledge_base=quantized-unquantized-midi-difference\" target=\"_blank\" rel=\"noreferrer noopener\">fichier MIDI non quantifi\u00e9<\/a> par la suite, vous pouvez alors changer de tempo comme bon vous semble et ignorer la partition affich\u00e9e dans le <a href=\"\/?knowledge_base=transcription-viewer\" target=\"_blank\" rel=\"noreferrer noopener\">visualiseur de transcription<\/a>. <\/li>\n\n\n\n<li><strong>Jeu pr\u00e9cis : <\/strong>Si vous vous enregistrez en train de jouer, assurez-vous de jouer plut\u00f4t lentement et avec pr\u00e9cision. Vous pouvez utiliser la <a href=\"\/?knowledge_base=record-mobile\" target=\"_blank\" rel=\"noreferrer noopener\">fonction d&#8217;enregistrement int\u00e9gr\u00e9e avec le m\u00e9tronome des applications Klangio<\/a> pour ce faire. N&#8217;h\u00e9sitez pas \u00e0 faire plusieurs essais pour obtenir une bonne prise, vous verrez que cela en vaut la peine \ud83d\ude42  <\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\">Ajouter des informations suppl\u00e9mentaires<\/h2>\n\n<p class=\"wp-block-paragraph\">Pendant l&#8217;<a href=\"\/?knowledge_base=transcription-wizard\" target=\"_blank\" rel=\"noreferrer noopener\">Assistant<\/a> <a href=\"\/?doc_category=transcription-wizard\" target=\"_blank\" rel=\"noreferrer noopener\">de transcription<\/a>, il vous est demand\u00e9 d&#8217;<a href=\"\/?knowledge_base=additional-information\" target=\"_blank\" rel=\"noreferrer noopener\">ajouter des informations suppl\u00e9mentaires<\/a> \u00e0 la musique. Cela peut consid\u00e9rablement am\u00e9liorer la qualit\u00e9 de la transcription. Vous pouvez \u00e9galement acc\u00e9der \u00e0 la <a href=\"\/?knowledge_base=retranscribe\" target=\"_blank\" rel=\"noreferrer noopener\">fonction de retranscription<\/a> dans le <a href=\"\/?knowledge_base=songbook\" target=\"_blank\" rel=\"noreferrer noopener\">carnet de chansons de votre compte Klangio<\/a>, pour modifier les informations suppl\u00e9mentaires m\u00eame apr\u00e8s que la transcription soit d\u00e9j\u00e0 termin\u00e9e.  <\/p>\n\n<h2 class=\"wp-block-heading\">Utiliser le mode d&#8217;\u00e9dition<\/h2>\n\n<p class=\"wp-block-paragraph\">Gardez \u00e0 l&#8217;esprit que dans la transcription musicale, l&#8217;interpr\u00e9tation personnelle joue un r\u00f4le \u00e9norme. C&#8217;est pourquoi nous avons introduit le <a href=\"\/?knowledge_base=edit-mode\" target=\"_blank\" rel=\"noreferrer noopener\">Mode d&#8217;\u00c9dition<\/a>, qui vous permet d&#8217;adapter la partition en quelques clics seulement. <\/p>\n\n<h2 class=\"wp-block-heading\">Remboursement de votre transcription<\/h2>\n\n<h3 class=\"wp-block-heading\">Rembourser un ticket de transcription sur votre compte<\/h3>\n\n<p class=\"wp-block-paragraph\">Si vous \u00eates toujours insatisfait de la qualit\u00e9 de votre transcription, vous pouvez simplement <a href=\"\/?knowledge_base=refund-a-transcription\" target=\"_blank\" rel=\"noreferrer noopener\">demander le remboursement complet de votre transcription<\/a> dans le <a href=\"\/?knowledge_base=songbook\" target=\"_blank\" rel=\"noreferrer noopener\">r\u00e9pertoire de votre compte Klangio<\/a> et r\u00e9essayer avec un morceau de musique diff\u00e9rent. Avec cette option, votre transcription sera supprim\u00e9e et le ticket sera \u00e0 nouveau disponible dans votre compte Klangio. Votre paiement n&#8217;est pas rembours\u00e9 avec cette fonctionnalit\u00e9. <\/p>\n\n<h3 class=\"wp-block-heading\">Rembourser votre paiement de transcription<\/h3>\n\n<p class=\"wp-block-paragraph\">Si vous souhaitez rembourser votre paiement, utilisez simplement notre site web <a href=\"https:\/\/klang.io\/request-refund\/\" target=\"_blank\" rel=\"noreferrer noopener\">Demander un remboursement<\/a>. Avec cela, votre transcription sera supprim\u00e9e, et le ticket ne sera plus disponible sur votre compte Klangio. Votre paiement sera rembours\u00e9 apr\u00e8s que notre \u00e9quipe de support aura approuv\u00e9 votre demande.<\/p>\n\n<p class=\"wp-block-paragraph\">N&#8217;h\u00e9sitez pas \u00e0 consulter les autres articles de notre <a href=\"https:\/\/klang.io\/help\">Centre d&#8217;Aide<\/a> si vous avez des questions sur la fa\u00e7on d&#8217;am\u00e9liorer la qualit\u00e9 de la transcription avec les applications Klangio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si vous avez des difficult\u00e9s \u00e0 obtenir des notes utiles \u00e0 partir d&#8217;une transcription Klangio, alors cet article peut vous aider. Je vais vous montrer comment am\u00e9liorer la qualit\u00e9 de vos transcriptions. Limites des applications Assurez-vous d&#8217;\u00eatre conscient des limites de chaque application. Vous pouvez en apprendre davantage ici. Qualit\u00e9 de l&#8217;audio Une bonne transcription [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":18747,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"doc_category":[527,479],"doc_tag":[],"knowledge_base":[483,481,484,507,480,482],"class_list":["post-32365","docs","type-docs","status-publish","has-post-thumbnail","hentry","doc_category-depannage","doc_category-transcription","knowledge_base-drum2notes-fr","knowledge_base-guitar2tabs-fr","knowledge_base-klangio-transcription-studio-fr","knowledge_base-melody-scanner-fr","knowledge_base-piano2notes-fr","knowledge_base-sing2notes-fr"],"year_month":"2026-07","word_count":573,"total_views":"530","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"Christoph Zimmer","author_nicename":"chris","author_url":"https:\/\/klang.io\/fr\/blog\/author\/chris\/"},"doc_category_info":[{"term_name":"D\u00e9pannage","term_url":"https:\/\/klang.io\/fr\/help\/non-knowledgebase\/depannage\/"},{"term_name":"Transcription","term_url":"https:\/\/klang.io\/fr\/help\/non-knowledgebase\/transcription\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comment am\u00e9liorer la qualit\u00e9 de la transcription | klang.io<\/title>\n<meta name=\"description\" content=\"Apprenez \u00e0 am\u00e9liorer la qualit\u00e9 de votre Klangio Transcription. D\u00e9couvrez quels types d&#039;audio fonctionnent le mieux et comment \u00e9diter les notes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/klang.io\/fr\/help\/improve-quality\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment am\u00e9liorer la qualit\u00e9 de la transcription | klang.io\" \/>\n<meta property=\"og:description\" content=\"Apprenez \u00e0 am\u00e9liorer la qualit\u00e9 de votre Klangio Transcription. D\u00e9couvrez quels types d&#039;audio fonctionnent le mieux et comment \u00e9diter les notes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/klang.io\/fr\/help\/improve-quality\/\" \/>\n<meta property=\"og:site_name\" content=\"klang.io\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/klangio\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-23T09:51:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/improve-quality.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@klangio\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/klang.io\/fr\/help\/improve-quality\/\",\"url\":\"https:\/\/klang.io\/fr\/help\/improve-quality\/\",\"name\":\"Comment am\u00e9liorer la qualit\u00e9 de la transcription | klang.io\",\"isPartOf\":{\"@id\":\"https:\/\/klang.io\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/klang.io\/fr\/help\/improve-quality\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/klang.io\/fr\/help\/improve-quality\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/improve-quality.png\",\"datePublished\":\"2024-04-24T09:48:41+00:00\",\"dateModified\":\"2025-10-23T09:51:24+00:00\",\"description\":\"Apprenez \u00e0 am\u00e9liorer la qualit\u00e9 de votre Klangio Transcription. D\u00e9couvrez quels types d'audio fonctionnent le mieux et comment \u00e9diter les notes.\",\"breadcrumb\":{\"@id\":\"https:\/\/klang.io\/fr\/help\/improve-quality\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/klang.io\/fr\/help\/improve-quality\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/klang.io\/fr\/help\/improve-quality\/#primaryimage\",\"url\":\"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/improve-quality.png\",\"contentUrl\":\"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/improve-quality.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/klang.io\/fr\/help\/improve-quality\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/klang.io\/fr\/home-2\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Help Center\",\"item\":\"https:\/\/klang.io\/fr\/help\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Comment am\u00e9liorer la qualit\u00e9 de la transcription\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/klang.io\/fr\/#website\",\"url\":\"https:\/\/klang.io\/fr\/\",\"name\":\"Klangio\",\"description\":\"AI Tools for Musicians\",\"publisher\":{\"@id\":\"https:\/\/klang.io\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/klang.io\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/klang.io\/fr\/#organization\",\"name\":\"Klangio GmbH\",\"url\":\"https:\/\/klang.io\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/klang.io\/fr\/#\/schema\/logo\/image\/\",\"url\":\"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png\",\"contentUrl\":\"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png\",\"width\":512,\"height\":512,\"caption\":\"Klangio GmbH\"},\"image\":{\"@id\":\"https:\/\/klang.io\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/klangio\",\"https:\/\/x.com\/klangio\",\"https:\/\/www.linkedin.com\/company\/klangio\/\",\"https:\/\/www.instagram.com\/klangio\/\",\"https:\/\/www.youtube.com\/@Klangio\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment am\u00e9liorer la qualit\u00e9 de la transcription | klang.io","description":"Apprenez \u00e0 am\u00e9liorer la qualit\u00e9 de votre Klangio Transcription. D\u00e9couvrez quels types d'audio fonctionnent le mieux et comment \u00e9diter les notes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/klang.io\/fr\/help\/improve-quality\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment am\u00e9liorer la qualit\u00e9 de la transcription | klang.io","og_description":"Apprenez \u00e0 am\u00e9liorer la qualit\u00e9 de votre Klangio Transcription. D\u00e9couvrez quels types d'audio fonctionnent le mieux et comment \u00e9diter les notes.","og_url":"https:\/\/klang.io\/fr\/help\/improve-quality\/","og_site_name":"klang.io","article_publisher":"https:\/\/facebook.com\/klangio","article_modified_time":"2025-10-23T09:51:24+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/improve-quality.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@klangio","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/klang.io\/fr\/help\/improve-quality\/","url":"https:\/\/klang.io\/fr\/help\/improve-quality\/","name":"Comment am\u00e9liorer la qualit\u00e9 de la transcription | klang.io","isPartOf":{"@id":"https:\/\/klang.io\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/klang.io\/fr\/help\/improve-quality\/#primaryimage"},"image":{"@id":"https:\/\/klang.io\/fr\/help\/improve-quality\/#primaryimage"},"thumbnailUrl":"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/improve-quality.png","datePublished":"2024-04-24T09:48:41+00:00","dateModified":"2025-10-23T09:51:24+00:00","description":"Apprenez \u00e0 am\u00e9liorer la qualit\u00e9 de votre Klangio Transcription. D\u00e9couvrez quels types d'audio fonctionnent le mieux et comment \u00e9diter les notes.","breadcrumb":{"@id":"https:\/\/klang.io\/fr\/help\/improve-quality\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/klang.io\/fr\/help\/improve-quality\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/klang.io\/fr\/help\/improve-quality\/#primaryimage","url":"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/improve-quality.png","contentUrl":"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/improve-quality.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/klang.io\/fr\/help\/improve-quality\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/klang.io\/fr\/home-2\/"},{"@type":"ListItem","position":2,"name":"Help Center","item":"https:\/\/klang.io\/fr\/help\/"},{"@type":"ListItem","position":3,"name":"Comment am\u00e9liorer la qualit\u00e9 de la transcription"}]},{"@type":"WebSite","@id":"https:\/\/klang.io\/fr\/#website","url":"https:\/\/klang.io\/fr\/","name":"Klangio","description":"AI Tools for Musicians","publisher":{"@id":"https:\/\/klang.io\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/klang.io\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/klang.io\/fr\/#organization","name":"Klangio GmbH","url":"https:\/\/klang.io\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/klang.io\/fr\/#\/schema\/logo\/image\/","url":"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png","contentUrl":"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png","width":512,"height":512,"caption":"Klangio GmbH"},"image":{"@id":"https:\/\/klang.io\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/klangio","https:\/\/x.com\/klangio","https:\/\/www.linkedin.com\/company\/klangio\/","https:\/\/www.instagram.com\/klangio\/","https:\/\/www.youtube.com\/@Klangio"]}]}},"knowledge_base_info":[{"term_name":"Drum2Notes","term_url":"https:\/\/klang.io\/fr\/help\/drum2notes-fr\/","term_slug":"drum2notes-fr"},{"term_name":"Guitar2Tabs","term_url":"https:\/\/klang.io\/fr\/help\/guitar2tabs-fr\/","term_slug":"guitar2tabs-fr"},{"term_name":"Klangio Transcription Studio","term_url":"https:\/\/klang.io\/fr\/help\/klangio-transcription-studio-fr\/","term_slug":"klangio-transcription-studio-fr"},{"term_name":"Melody Scanner","term_url":"https:\/\/klang.io\/fr\/help\/melody-scanner-fr\/","term_slug":"melody-scanner-fr"},{"term_name":"Piano2Notes","term_url":"https:\/\/klang.io\/fr\/help\/piano2notes-fr\/","term_slug":"piano2notes-fr"},{"term_name":"Sing2Notes","term_url":"https:\/\/klang.io\/fr\/help\/sing2notes-fr\/","term_slug":"sing2notes-fr"}],"knowledge_base_slug":["drum2notes-fr","guitar2tabs-fr","klangio-transcription-studio-fr","melody-scanner-fr","piano2notes-fr","sing2notes-fr"],"_links":{"self":[{"href":"https:\/\/klang.io\/fr\/wp-json\/wp\/v2\/docs\/32365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/klang.io\/fr\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/klang.io\/fr\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/klang.io\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/klang.io\/fr\/wp-json\/wp\/v2\/comments?post=32365"}],"version-history":[{"count":3,"href":"https:\/\/klang.io\/fr\/wp-json\/wp\/v2\/docs\/32365\/revisions"}],"predecessor-version":[{"id":39523,"href":"https:\/\/klang.io\/fr\/wp-json\/wp\/v2\/docs\/32365\/revisions\/39523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/klang.io\/fr\/wp-json\/wp\/v2\/media\/18747"}],"wp:attachment":[{"href":"https:\/\/klang.io\/fr\/wp-json\/wp\/v2\/media?parent=32365"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/klang.io\/fr\/wp-json\/wp\/v2\/doc_category?post=32365"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/klang.io\/fr\/wp-json\/wp\/v2\/doc_tag?post=32365"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/klang.io\/fr\/wp-json\/wp\/v2\/knowledge_base?post=32365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}