{"id":32766,"date":"2024-03-26T08:22:19","date_gmt":"2024-03-26T08:22:19","guid":{"rendered":"https:\/\/klang.io\/help\/edit-mode\/"},"modified":"2025-09-08T05:16:43","modified_gmt":"2025-09-08T05:16:43","password":"","slug":"edit-mode","status":"publish","type":"docs","link":"https:\/\/klang.io\/fr\/help\/edit-mode\/","title":{"rendered":"Comment utiliser le mode \u00e9dition"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dans ce guide, vous d\u00e9couvrirez toutes les fonctionnalit\u00e9s du mode \u00c9dition, incluses dans votre <a href=\"\/?knowledge_base=what-music-transcribe\" target=\"_blank\" rel=\"noreferrer noopener\">Klangio Transcription<\/a>.<\/p>\n\n<p class=\"wp-block-paragraph\">Continuez \u00e0 lire, ou regardez le tutoriel YouTube :<\/p>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Adjust Notes with the Edit Mode | The Ultimate Guide to Klangio\" width=\"800\" height=\"450\" data-src=\"https:\/\/www.youtube.com\/embed\/dYmynrgyhiE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe>\n<\/div><\/figure>\n\n<h2 class=\"wp-block-heading\">Ouverture du mode \u00e9dition<\/h2>\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"810\" height=\"410\" src=\"\/wp-content\/uploads\/2024\/03\/image-10.png\" alt=\"Vous pouvez trouver le mode &#xE9;dition dans le coin sup&#xE9;rieur gauche de votre transcription.\" class=\"wp-image-29119\" style=\"width:593px;height:auto\" srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-10.png 810w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-10-300x152.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-10-768x389.png 768w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-10-360x182.png 360w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><figcaption class=\"wp-element-caption\">Vous pouvez trouver le mode \u00e9dition dans le coin sup\u00e9rieur gauche de votre transcription.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Vous pouvez trouver le <strong>mode \u00e9dition<\/strong> dans le coin sup\u00e9rieur gauche de votre transcription.<\/p>\n\n<p class=\"wp-block-paragraph\">Cliquez sur le bouton <strong>Mode \u00e9dition<\/strong> dans le coin sup\u00e9rieur gauche de votre visualiseur de transcription pour ouvrir le mode \u00e9dition. Il est disponible pour <a href=\"\/?knowledge_base=get-started\" target=\"_blank\" rel=\"noreferrer noopener\">toutes les applications Klangio<\/a>. Assurez-vous de <a href=\"\/?knowledge_base=demo-to-full-transcription\" target=\"_blank\" rel=\"noreferrer noopener\">passer \u00e0 une <strong>transcription compl\u00e8te<\/strong><\/a> pour d\u00e9bloquer le mode \u00e9dition avant de commencer.  <\/p>\n\n<p class=\"wp-block-paragraph\">Le mode \u00e9dition est un outil puissant pour personnaliser vos transcriptions et corriger les erreurs. Le mode \u00e9dition n&#8217;est disponible que pour la <strong>version Web<\/strong> des applications Klangio.<\/p>\n\n<h2 class=\"wp-block-heading\">Aper\u00e7u des fonctionnalit\u00e9s<\/h2>\n\n<h3 class=\"wp-block-heading\">Supprimer des notes<\/h3>\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" width=\"991\" height=\"525\" data-src=\"\/wp-content\/uploads\/2024\/03\/image-11.png\" alt=\"S&#xE9;lectionnez une note et cliquez sur l'ic&#xF4;ne de la corbeille, ou appuyez sur la touche &#xAB; supprimer &#xBB; pour retirer une note.\" class=\"wp-image-29129 lazyload\" style=\"--smush-placeholder-width: 991px; --smush-placeholder-aspect-ratio: 991\/525;width:487px;height:auto\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-11.png 991w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-11-300x159.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-11-768x407.png 768w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-11-360x191.png 360w\" data-sizes=\"(max-width: 991px) 100vw, 991px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">S\u00e9lectionnez une note et cliquez sur l&#8217;ic\u00f4ne de la corbeille, ou appuyez sur la touche \u00ab supprimer \u00bb pour retirer une note.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Pour <strong>supprimer une note<\/strong> :<\/p>\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li>S\u00e9lectionnez l&#8217;<strong>outil de s\u00e9lection<\/strong> (ic\u00f4ne du curseur).<\/li>\n\n\n\n<li>Cliquez sur la note que vous voulez supprimer.<\/li>\n\n\n\n<li>Appuyez sur la <strong>touche Supprimer<\/strong> de votre clavier ou cliquez sur l&#8217;<strong>ic\u00f4ne de la corbeille<\/strong>.<\/li>\n<\/ol>\n\n<h3 class=\"wp-block-heading\">Ajouter des notes<\/h3>\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" width=\"778\" height=\"310\" data-src=\"\/wp-content\/uploads\/2024\/03\/image-12.png\" alt=\"Utilisez l'outil Ajouter des notes et cliquez sur un endroit de votre partition pour ajouter une note.\" class=\"wp-image-29137 lazyload\" style=\"--smush-placeholder-width: 778px; --smush-placeholder-aspect-ratio: 778\/310;width:550px;height:auto\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-12.png 778w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-12-300x120.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-12-768x306.png 768w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-12-360x143.png 360w\" data-sizes=\"(max-width: 778px) 100vw, 778px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">Utilisez l&#8217;outil Ajouter des notes et cliquez sur un endroit de votre partition pour ajouter une note.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Pour <strong>ajouter une nouvelle note<\/strong> :<\/p>\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li>Utilisez l&#8217;<strong>outil Ajouter des notes<\/strong> (Note avec une ic\u00f4ne \u00ab + \u00bb).<\/li>\n\n\n\n<li>Choisissez la <strong>dur\u00e9e de la note<\/strong> en utilisant les boutons sur le c\u00f4t\u00e9 droit.<\/li>\n\n\n\n<li>Cliquez sur l&#8217;endroit de la partition o\u00f9 vous voulez placer la note.<\/li>\n<\/ol>\n\n<h3 class=\"wp-block-heading\">Changer la hauteur de la note<\/h3>\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" width=\"775\" height=\"442\" data-src=\"\/wp-content\/uploads\/2024\/03\/image-13.png\" alt=\"S&#xE9;lectionnez une note et faites-la glisser vers le haut ou le bas, ou utilisez les touches fl&#xE9;ch&#xE9;es pour changer la hauteur.\" class=\"wp-image-29145 lazyload\" style=\"--smush-placeholder-width: 775px; --smush-placeholder-aspect-ratio: 775\/442;width:459px;height:auto\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-13.png 775w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-13-300x171.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-13-768x438.png 768w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-13-360x205.png 360w\" data-sizes=\"(max-width: 775px) 100vw, 775px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">S\u00e9lectionnez une note et faites-la glisser vers le haut ou le bas, ou utilisez les touches fl\u00e9ch\u00e9es pour changer la hauteur.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Pour <strong>changer la hauteur d&#8217;une note<\/strong> :<\/p>\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li>S\u00e9lectionnez l&#8217;<strong>outil de s\u00e9lection<\/strong>.<\/li>\n\n\n\n<li>Cliquez sur la note et <strong>faites-la glisser vers le haut ou le bas<\/strong> pour ajuster la hauteur.<\/li>\n\n\n\n<li>Pour des ajustements plus pr\u00e9cis, utilisez les <strong>touches fl\u00e9ch\u00e9es Haut et Bas<\/strong>.<\/li>\n<\/ol>\n\n<h3 class=\"wp-block-heading\">Ajuster la dur\u00e9e de la note<\/h3>\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" width=\"950\" height=\"401\" data-src=\"\/wp-content\/uploads\/2024\/03\/image-14.png\" alt=\"S&#xE9;lectionnez une note puis utilisez ces boutons pour ajuster la dur&#xE9;e.\" class=\"wp-image-29153 lazyload\" style=\"--smush-placeholder-width: 950px; --smush-placeholder-aspect-ratio: 950\/401;width:628px;height:auto\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-14.png 950w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-14-300x127.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-14-768x324.png 768w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-14-360x152.png 360w\" data-sizes=\"(max-width: 950px) 100vw, 950px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">S\u00e9lectionnez une note puis utilisez ces boutons pour ajuster la dur\u00e9e.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Lorsqu&#8217;une note est s\u00e9lectionn\u00e9e, vous pouvez \u00e9galement :<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Changer sa <strong>dur\u00e9e<\/strong>.<\/li>\n\n\n\n<li>En faire une <strong>note point\u00e9e<\/strong> ou un <strong>triolet<\/strong>.<\/li>\n\n\n\n<li>Ajouter une <strong>liaison<\/strong>.<\/li>\n\n\n\n<li>Convertir la note en <strong>silence<\/strong>.<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\">Copier et coller des notes<\/h3>\n\n<p class=\"wp-block-paragraph\">Vous pouvez <strong>copier et coller des notes<\/strong> en utilisant les raccourcis familiers :<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Ctrl + C<\/strong> pour copier.<\/li>\n\n\n\n<li><strong>Ctrl + V<\/strong> pour coller.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Pour s\u00e9lectionner plusieurs notes :<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Dessinez un cadre<\/strong> autour des notes en utilisant l&#8217;<strong>outil de s\u00e9lection<\/strong>.<\/li>\n\n\n\n<li>Ou <strong>cliquez sur un endroit vide<\/strong> dans une mesure pour s\u00e9lectionner toutes les notes de cette mesure.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Vous pouvez \u00e9galement d\u00e9placer plusieurs notes vers le haut ou le bas en utilisant les <strong>touches Haut et Bas<\/strong>.<\/p>\n\n<h3 class=\"wp-block-heading\">Transposer la tonalit\u00e9<\/h3>\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" width=\"562\" height=\"462\" data-src=\"\/wp-content\/uploads\/2024\/03\/image-16.png\" alt=\"Transposez votre transcription en cliquant sur le symbole de l'armure.\" class=\"wp-image-29169 lazyload\" style=\"--smush-placeholder-width: 562px; --smush-placeholder-aspect-ratio: 562\/462;width:442px;height:auto\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-16.png 562w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-16-300x247.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-16-360x296.png 360w\" data-sizes=\"(max-width: 562px) 100vw, 562px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">Transposez votre transcription en cliquant sur le symbole de l&#8217;armure.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Pour <strong>transposer la tonalit\u00e9<\/strong> :<\/p>\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li>Cliquez sur l&#8217;armure de la partition.<\/li>\n\n\n\n<li>Utilisez les boutons <strong>+<\/strong> et <strong>&#8211;<\/strong> pour d\u00e9caler la transcription vers le haut ou le bas par demi-tons.<\/li>\n<\/ol>\n\n<p class=\"wp-block-paragraph\">C&#8217;est particuli\u00e8rement utile pour les guitaristes car cela imite l&#8217;utilisation d&#8217;un capodastre.<\/p>\n\n<h3 class=\"wp-block-heading\">Changer la signature rythmique<\/h3>\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" width=\"699\" height=\"489\" data-src=\"\/wp-content\/uploads\/2024\/03\/image-15.png\" alt=\"Cliquez sur le symbole de la mesure pour changer la signature rythmique.\" class=\"wp-image-29161 lazyload\" style=\"--smush-placeholder-width: 699px; --smush-placeholder-aspect-ratio: 699\/489;width:392px;height:auto\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-15.png 699w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-15-300x210.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-15-360x252.png 360w\" data-sizes=\"(max-width: 699px) 100vw, 699px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">Cliquez sur le symbole de la mesure pour changer la signature rythmique.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Pour <strong>ajuster la signature rythmique<\/strong> :<\/p>\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li>Cliquez sur le bouton <strong>Signature rythmique<\/strong>.<\/li>\n\n\n\n<li>S\u00e9lectionnez la signature rythmique correcte \u2014 que ce soit <strong>4\/4<\/strong>, <strong>3\/4<\/strong>, ou une autre option.<\/li>\n<\/ol>\n\n<h2 class=\"wp-block-heading\">Fonctionnalit\u00e9s d&#8217;\u00e9dition sp\u00e9cifiques \u00e0 l&#8217;application<\/h2>\n\n<h3 class=\"wp-block-heading\">\u00c9diter les tablatures de guitare<\/h3>\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" width=\"857\" height=\"489\" data-src=\"\/wp-content\/uploads\/2024\/03\/image-18.png\" alt=\"Cliquez sur un endroit vide dans vos tablatures pour ajouter une nouvelle note.\" class=\"wp-image-29193 lazyload\" style=\"--smush-placeholder-width: 857px; --smush-placeholder-aspect-ratio: 857\/489;width:570px;height:auto\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-18.png 857w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-18-300x171.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-18-768x438.png 768w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-18-360x205.png 360w\" data-sizes=\"(max-width: 857px) 100vw, 857px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">Cliquez sur un endroit vide dans vos tablatures pour ajouter une nouvelle note.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Pour les transcriptions <strong>Guitar2Tabs<\/strong> et <strong>Klangio Transcription Studio<\/strong>\u00a0:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Modifiez les notes<\/strong> en cliquant sur les <strong>tablatures<\/strong>.<\/li>\n\n\n\n<li>Ajoutez de nouvelles notes en tapant le <strong>num\u00e9ro de frette<\/strong> dans la case qui appara\u00eet.<\/li>\n\n\n\n<li>Ajustez les r\u00e9glages du <strong>capodastre<\/strong> et de l&#8217;<strong>accordage<\/strong> directement dans le mode \u00e9dition.<\/li>\n<\/ul>\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" width=\"584\" height=\"314\" data-src=\"\/wp-content\/uploads\/2024\/03\/image-19.png\" alt=\"Cliquez sur vos param&#xE8;tres de partition sp&#xE9;cifiques &#xE0; la guitare pour les ajuster.\" class=\"wp-image-29201 lazyload\" style=\"--smush-placeholder-width: 584px; --smush-placeholder-aspect-ratio: 584\/314;width:372px;height:auto\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-19.png 584w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-19-300x161.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-19-360x194.png 360w\" data-sizes=\"(max-width: 584px) 100vw, 584px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">Cliquez sur vos param\u00e8tres de partition sp\u00e9cifiques \u00e0 la guitare pour les ajuster.<\/figcaption><\/figure>\n\n<h3 class=\"wp-block-heading\">\u00c9diter les paroles<\/h3>\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" width=\"725\" height=\"372\" data-src=\"\/wp-content\/uploads\/2024\/03\/image-20.png\" alt=\"Cliquez sur la barre de paroles sous la partition pour &#xE9;diter les paroles.\" class=\"wp-image-29209 lazyload\" style=\"--smush-placeholder-width: 725px; --smush-placeholder-aspect-ratio: 725\/372;width:493px;height:auto\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-20.png 725w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-20-300x154.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-20-360x185.png 360w\" data-sizes=\"(max-width: 725px) 100vw, 725px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">Cliquez sur la barre de paroles sous la partition pour \u00e9diter les paroles.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Pour les transcriptions <strong>Sing2Notes<\/strong> et <strong>Klangio Transcription Studio<\/strong>\u00a0:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Modifiez les paroles<\/strong> en cliquant sur le texte et en le modifiant dans la bo\u00eete pop-up.<\/li>\n\n\n\n<li>Pour <strong>supprimer des paroles<\/strong>, il suffit de vider la zone de texte et de la laisser vide.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\">Raccourcis clavier<\/h2>\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" width=\"596\" height=\"517\" data-src=\"\/wp-content\/uploads\/2024\/03\/image-22.png\" alt=\"Cliquez sur l'ic&#xF4;ne &#xAB; ? &#xBB; pour ouvrir la liste des raccourcis.\" class=\"wp-image-29225 lazyload\" style=\"--smush-placeholder-width: 596px; --smush-placeholder-aspect-ratio: 596\/517;width:431px;height:auto\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-22.png 596w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-22-300x260.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-22-360x312.png 360w\" data-sizes=\"(max-width: 596px) 100vw, 596px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">Cliquez sur l&#8217;ic\u00f4ne \u00ab ? \u00bb pour ouvrir la liste des raccourcis.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Cliquez sur l&#8217;ic\u00f4ne \u00ab ? \u00bb en haut de votre \u00e9cran pour ouvrir la liste des raccourcis. Ces raccourcis peuvent vous aider \u00e0 travailler plus efficacement avec l&#8217;\u00e9diteur. <\/p>\n\n<h2 class=\"wp-block-heading\">Param\u00e8tres de partition suppl\u00e9mentaires<\/h2>\n\n<p class=\"wp-block-paragraph\">Vous pouvez ajuster d&#8217;autres param\u00e8tres qui affectent l&#8217;ensemble de la partition de transcription. Actuellement, les param\u00e8tres de partition suivants sont disponibles : <\/p>\n\n<ul class=\"wp-block-list\">\n<li>Transposer la tonalit\u00e9<\/li>\n\n\n\n<li>Changer la dur\u00e9e des notes<\/li>\n\n\n\n<li>S\u00e9lectionner un point de s\u00e9paration (Piano2Notes uniquement)<\/li>\n\n\n\n<li>Changer la signature rythmique<\/li>\n\n\n\n<li>Ajuster la mesure d&#8217;introduction<\/li>\n<\/ul>\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" width=\"378\" height=\"440\" data-src=\"\/wp-content\/uploads\/2024\/03\/grafik-115.png\" alt=\"Les param&#xE8;tres de partition du mode &#xE9;dition de Klangio\" class=\"wp-image-17365 lazyload\" style=\"--smush-placeholder-width: 378px; --smush-placeholder-aspect-ratio: 378\/440;width:296px;height:auto\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/grafik-115.png 378w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/grafik-115-258x300.png 258w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/grafik-115-360x419.png 360w\" data-sizes=\"(max-width: 378px) 100vw, 378px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">Les param\u00e8tres disponibles du mode \u00e9dition<\/figcaption><\/figure>\n\n<h3 class=\"wp-block-heading\">Transposer la tonalit\u00e9<\/h3>\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" width=\"486\" height=\"476\" data-src=\"\/wp-content\/uploads\/2024\/03\/grafik-116.png\" alt=\"Le menu &#xAB; Transposer la partition &#xBB; du mode &#xE9;dition de Klangio\" class=\"wp-image-17370 lazyload\" style=\"--smush-placeholder-width: 486px; --smush-placeholder-aspect-ratio: 486\/476;width:429px;height:auto\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/grafik-116.png 486w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/grafik-116-300x294.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/grafik-116-360x353.png 360w\" data-sizes=\"(max-width: 486px) 100vw, 486px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">Entrez le nombre de demi-tons dont vous voulez transposer votre morceau<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Transposer la tonalit\u00e9 de votre transcription d\u00e9cale essentiellement toutes les notes jou\u00e9es du nombre de demi-tons que vous avez s\u00e9lectionn\u00e9. Pour les guitaristes, c&#8217;est comme utiliser un <a href=\"https:\/\/www.fender.com\/articles\/parts-and-accessories\/what-is-a-capo\">capodastre<\/a>. Cela peut \u00eatre tr\u00e8s pratique si vous voulez que votre transcription corresponde ensuite \u00e0 une chanson dans une tonalit\u00e9 diff\u00e9rente. Cliquez simplement sur + et &#8211; pour ajuster le nombre de demi-tons dont vous voulez accorder la transcription vers le haut ou vers le bas. Les notes affich\u00e9es s&#8217;ajusteront alors apr\u00e8s que vous aurez cliqu\u00e9 sur transposer.    <\/p>\n\n<h3 class=\"wp-block-heading\">Changer la dur\u00e9e des notes<\/h3>\n\n<p class=\"wp-block-paragraph\">Si le tempo a \u00e9t\u00e9 d\u00e9tect\u00e9 \u00e0 la moiti\u00e9 ou au double du BPM que vous aviez pr\u00e9vu, ce r\u00e9glage peut vous aider. En cliquant sur \u00ab 2.0x \u00bb, vous pouvez \u00e9tirer les notes, et en cliquant sur \u00ab 0.5x \u00bb, vous les compressez de moiti\u00e9. <\/p>\n\n<h3 class=\"wp-block-heading\">S\u00e9lectionner un point de s\u00e9paration (Piano2Notes uniquement)<\/h3>\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" width=\"489\" height=\"429\" data-src=\"\/wp-content\/uploads\/2024\/03\/grafik-117.png\" alt=\"Le menu &#xAB; Point de s&#xE9;paration &#xBB; du mode &#xE9;dition de Klangio\" class=\"wp-image-17397 lazyload\" style=\"--smush-placeholder-width: 489px; --smush-placeholder-aspect-ratio: 489\/429;width:318px;height:auto\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/grafik-117.png 489w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/grafik-117-300x263.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/grafik-117-360x316.png 360w\" data-sizes=\"(max-width: 489px) 100vw, 489px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">S\u00e9lectionnez le point de s\u00e9paration<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Le point de s\u00e9paration d\u00e9termine la s\u00e9paration entre les notes jou\u00e9es par chaque main sur le piano. Choisir un point de s\u00e9paration plus \u00e9lev\u00e9 signifie que la main gauche couvrira une plus grande gamme de notes et vice versa. Cliquez simplement sur le bouton \u00ab + \u00bb ou \u00ab &#8211; \u00bb pour le modifier. L&#8217;aper\u00e7u affichera comment votre partition changera. Une fois termin\u00e9, cliquez sur \u00ab APPLIQUER \u00bb.    <\/p>\n\n<h3 class=\"wp-block-heading\">Changer la signature rythmique<\/h3>\n\n<p class=\"wp-block-paragraph\">Le plus souvent, la signature rythmique 4\/4 est utilis\u00e9e, en particulier dans les chansons pop. Cependant, si l&#8217;IA ne l&#8217;a pas estim\u00e9e correctement, vous pouvez basculer entre celle-ci et la signature rythmique 3\/4 en cliquant sur ces boutons. <\/p>\n\n<h3 class=\"wp-block-heading\">Ajuster la mesure d&#8217;introduction<\/h3>\n\n<p class=\"wp-block-paragraph\">Ce r\u00e9glage vous permet essentiellement de d\u00e9caler toutes vos notes plus \u00e0 gauche ou \u00e0 droite, en cliquant sur les boutons fl\u00e9ch\u00e9s. Cela vous permet d&#8217;ajuster quelle note est celle de la mesure, au cas o\u00f9 elle n&#8217;aurait pas \u00e9t\u00e9 d\u00e9tect\u00e9e correctement. <\/p>\n\n<h2 class=\"wp-block-heading\">Enregistrer et annuler les modifications<\/h2>\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" width=\"751\" height=\"297\" data-src=\"\/wp-content\/uploads\/2024\/03\/image-21.png\" alt=\"Utilisez les boutons annuler, r&#xE9;tablir et enregistrer dans le coin sup&#xE9;rieur droit.\" class=\"wp-image-29217 lazyload\" style=\"--smush-placeholder-width: 751px; --smush-placeholder-aspect-ratio: 751\/297;width:503px;height:auto\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-21.png 751w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-21-300x119.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/image-21-360x142.png 360w\" data-sizes=\"(max-width: 751px) 100vw, 751px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">Utilisez les boutons annuler, r\u00e9tablir et enregistrer dans le coin sup\u00e9rieur droit.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Vous pouvez <strong>annuler ou r\u00e9tablir<\/strong> vos modifications en utilisant les <strong>boutons d&#8217;historique des modifications<\/strong> en haut \u00e0 droite de l&#8217;\u00e9cran.<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Annuler<\/strong> : Cliquez sur la fl\u00e8che gauche.<\/li>\n\n\n\n<li><strong>R\u00e9tablir<\/strong> : Cliquez sur la fl\u00e8che droite.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Une fois que vous \u00eates satisfait de vos modifications, cliquez sur le <strong>bouton Enregistrer<\/strong> au milieu pour les valider.<\/p>\n\n<h2 class=\"wp-block-heading\">Vous ne trouvez pas de solution dans le mode \u00e9dition ?<\/h2>\n\n<p class=\"wp-block-paragraph\">Si vous avez du mal \u00e0 corriger une erreur dans votre transcription, consultez ce guide pour en savoir plus sur d&#8217;autres m\u00e9thodes pour <a href=\"\/?knowledge_base=improve-quality\" target=\"_blank\" rel=\"noreferrer noopener\">am\u00e9liorer la qualit\u00e9 de votre transcription<\/a><\/p>\n\n<p class=\"wp-block-paragraph\">N&#8217;h\u00e9sitez pas \u00e0 consulter les autres articles de notre <a href=\"https:\/\/klang.io\/help\" target=\"_blank\" rel=\"noreferrer noopener\">Centre d&#8217;aide<\/a> si vous avez des questions ou si vous souhaitez sugg\u00e9rer des fonctionnalit\u00e9s pour le mode \u00e9dition.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans ce guide, vous d\u00e9couvrirez toutes les fonctionnalit\u00e9s du mode \u00c9dition, incluses dans votre Klangio Transcription. Continuez \u00e0 lire, ou regardez le tutoriel YouTube : Ouverture du mode \u00e9dition Vous pouvez trouver le mode \u00e9dition dans le coin sup\u00e9rieur gauche de votre transcription. Cliquez sur le bouton Mode \u00e9dition dans le coin sup\u00e9rieur gauche de [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":29186,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"doc_category":[530],"doc_tag":[],"knowledge_base":[483,481,522,507,480,485,482],"class_list":["post-32766","docs","type-docs","status-publish","has-post-thumbnail","hentry","doc_category-visionneuse-de-transcription","knowledge_base-drum2notes-fr","knowledge_base-guitar2tabs-fr","knowledge_base-klangio-transcription-plugin-fr","knowledge_base-melody-scanner-fr","knowledge_base-piano2notes-fr","knowledge_base-scan2notes-fr","knowledge_base-sing2notes-fr"],"year_month":"2026-07","word_count":1286,"total_views":"544","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"Christoph Zimmer","author_nicename":"chris","author_url":"https:\/\/klang.io\/fr\/blog\/author\/chris\/"},"doc_category_info":[{"term_name":"Visionneuse de transcription","term_url":"https:\/\/klang.io\/fr\/help\/non-knowledgebase\/visionneuse-de-transcription\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comment utiliser le mode \u00e9dition | klang.io<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez les fonctions d&#039;\u00e9dition (tonalit\u00e9, tempo) de Klangio Transcription.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/klang.io\/fr\/help\/edit-mode\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment utiliser le mode \u00e9dition | klang.io\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez les fonctions d&#039;\u00e9dition (tonalit\u00e9, tempo) de Klangio Transcription.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/klang.io\/fr\/help\/edit-mode\/\" \/>\n<meta property=\"og:site_name\" content=\"klang.io\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/klangio\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-08T05:16:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/edit-mode-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@klangio\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/klang.io\/fr\/help\/edit-mode\/\",\"url\":\"https:\/\/klang.io\/fr\/help\/edit-mode\/\",\"name\":\"Comment utiliser le mode \u00e9dition | klang.io\",\"isPartOf\":{\"@id\":\"https:\/\/klang.io\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/klang.io\/fr\/help\/edit-mode\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/klang.io\/fr\/help\/edit-mode\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/edit-mode-1.png\",\"datePublished\":\"2024-03-26T08:22:19+00:00\",\"dateModified\":\"2025-09-08T05:16:43+00:00\",\"description\":\"D\u00e9couvrez les fonctions d'\u00e9dition (tonalit\u00e9, tempo) de Klangio Transcription.\",\"breadcrumb\":{\"@id\":\"https:\/\/klang.io\/fr\/help\/edit-mode\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/klang.io\/fr\/help\/edit-mode\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/klang.io\/fr\/help\/edit-mode\/#primaryimage\",\"url\":\"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/edit-mode-1.png\",\"contentUrl\":\"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/edit-mode-1.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/klang.io\/fr\/help\/edit-mode\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/klang.io\/fr\/home-2\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Help Center\",\"item\":\"https:\/\/klang.io\/fr\/help\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Comment utiliser le mode \u00e9dition\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/klang.io\/fr\/#website\",\"url\":\"https:\/\/klang.io\/fr\/\",\"name\":\"Klangio\",\"description\":\"AI Tools for Musicians\",\"publisher\":{\"@id\":\"https:\/\/klang.io\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/klang.io\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/klang.io\/fr\/#organization\",\"name\":\"Klangio GmbH\",\"url\":\"https:\/\/klang.io\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/klang.io\/fr\/#\/schema\/logo\/image\/\",\"url\":\"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png\",\"contentUrl\":\"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png\",\"width\":512,\"height\":512,\"caption\":\"Klangio GmbH\"},\"image\":{\"@id\":\"https:\/\/klang.io\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/klangio\",\"https:\/\/x.com\/klangio\",\"https:\/\/www.linkedin.com\/company\/klangio\/\",\"https:\/\/www.instagram.com\/klangio\/\",\"https:\/\/www.youtube.com\/@Klangio\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment utiliser le mode \u00e9dition | klang.io","description":"D\u00e9couvrez les fonctions d'\u00e9dition (tonalit\u00e9, tempo) de Klangio Transcription.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/klang.io\/fr\/help\/edit-mode\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment utiliser le mode \u00e9dition | klang.io","og_description":"D\u00e9couvrez les fonctions d'\u00e9dition (tonalit\u00e9, tempo) de Klangio Transcription.","og_url":"https:\/\/klang.io\/fr\/help\/edit-mode\/","og_site_name":"klang.io","article_publisher":"https:\/\/facebook.com\/klangio","article_modified_time":"2025-09-08T05:16:43+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/edit-mode-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@klangio","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/klang.io\/fr\/help\/edit-mode\/","url":"https:\/\/klang.io\/fr\/help\/edit-mode\/","name":"Comment utiliser le mode \u00e9dition | klang.io","isPartOf":{"@id":"https:\/\/klang.io\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/klang.io\/fr\/help\/edit-mode\/#primaryimage"},"image":{"@id":"https:\/\/klang.io\/fr\/help\/edit-mode\/#primaryimage"},"thumbnailUrl":"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/edit-mode-1.png","datePublished":"2024-03-26T08:22:19+00:00","dateModified":"2025-09-08T05:16:43+00:00","description":"D\u00e9couvrez les fonctions d'\u00e9dition (tonalit\u00e9, tempo) de Klangio Transcription.","breadcrumb":{"@id":"https:\/\/klang.io\/fr\/help\/edit-mode\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/klang.io\/fr\/help\/edit-mode\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/klang.io\/fr\/help\/edit-mode\/#primaryimage","url":"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/edit-mode-1.png","contentUrl":"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/edit-mode-1.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/klang.io\/fr\/help\/edit-mode\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/klang.io\/fr\/home-2\/"},{"@type":"ListItem","position":2,"name":"Help Center","item":"https:\/\/klang.io\/fr\/help\/"},{"@type":"ListItem","position":3,"name":"Comment utiliser le mode \u00e9dition"}]},{"@type":"WebSite","@id":"https:\/\/klang.io\/fr\/#website","url":"https:\/\/klang.io\/fr\/","name":"Klangio","description":"AI Tools for Musicians","publisher":{"@id":"https:\/\/klang.io\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/klang.io\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/klang.io\/fr\/#organization","name":"Klangio GmbH","url":"https:\/\/klang.io\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/klang.io\/fr\/#\/schema\/logo\/image\/","url":"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png","contentUrl":"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png","width":512,"height":512,"caption":"Klangio GmbH"},"image":{"@id":"https:\/\/klang.io\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/klangio","https:\/\/x.com\/klangio","https:\/\/www.linkedin.com\/company\/klangio\/","https:\/\/www.instagram.com\/klangio\/","https:\/\/www.youtube.com\/@Klangio"]}]}},"knowledge_base_info":[{"term_name":"Drum2Notes","term_url":"https:\/\/klang.io\/fr\/help\/drum2notes-fr\/","term_slug":"drum2notes-fr"},{"term_name":"Guitar2Tabs","term_url":"https:\/\/klang.io\/fr\/help\/guitar2tabs-fr\/","term_slug":"guitar2tabs-fr"},{"term_name":"Klangio Transcription Plugin","term_url":"https:\/\/klang.io\/fr\/help\/klangio-transcription-plugin-fr\/","term_slug":"klangio-transcription-plugin-fr"},{"term_name":"Melody Scanner","term_url":"https:\/\/klang.io\/fr\/help\/melody-scanner-fr\/","term_slug":"melody-scanner-fr"},{"term_name":"Piano2Notes","term_url":"https:\/\/klang.io\/fr\/help\/piano2notes-fr\/","term_slug":"piano2notes-fr"},{"term_name":"Scan2Notes","term_url":"https:\/\/klang.io\/fr\/help\/scan2notes-fr\/","term_slug":"scan2notes-fr"},{"term_name":"Sing2Notes","term_url":"https:\/\/klang.io\/fr\/help\/sing2notes-fr\/","term_slug":"sing2notes-fr"}],"knowledge_base_slug":["drum2notes-fr","guitar2tabs-fr","klangio-transcription-plugin-fr","melody-scanner-fr","piano2notes-fr","scan2notes-fr","sing2notes-fr"],"_links":{"self":[{"href":"https:\/\/klang.io\/fr\/wp-json\/wp\/v2\/docs\/32766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/klang.io\/fr\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/klang.io\/fr\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/klang.io\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/klang.io\/fr\/wp-json\/wp\/v2\/comments?post=32766"}],"version-history":[{"count":2,"href":"https:\/\/klang.io\/fr\/wp-json\/wp\/v2\/docs\/32766\/revisions"}],"predecessor-version":[{"id":38550,"href":"https:\/\/klang.io\/fr\/wp-json\/wp\/v2\/docs\/32766\/revisions\/38550"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/klang.io\/fr\/wp-json\/wp\/v2\/media\/29186"}],"wp:attachment":[{"href":"https:\/\/klang.io\/fr\/wp-json\/wp\/v2\/media?parent=32766"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/klang.io\/fr\/wp-json\/wp\/v2\/doc_category?post=32766"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/klang.io\/fr\/wp-json\/wp\/v2\/doc_tag?post=32766"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/klang.io\/fr\/wp-json\/wp\/v2\/knowledge_base?post=32766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}