{"id":32291,"date":"2024-05-22T09:36:19","date_gmt":"2024-05-22T09:36:19","guid":{"rendered":"https:\/\/klang.io\/help\/subscription-not-active\/"},"modified":"2025-09-08T05:17:53","modified_gmt":"2025-09-08T05:17:53","password":"","slug":"subscription-not-active","status":"publish","type":"docs","link":"https:\/\/klang.io\/it\/help\/subscription-not-active\/","title":{"rendered":"Il mio abbonamento a Klangio non \u00e8 attivo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Se hai appena effettuato l&#8217;upgrade al nostro abbonamento Pro per una qualsiasi delle app <a href=\"https:\/\/klang.io\/it\/\" target=\"_blank\" rel=\"noreferrer noopener\">Klangio<\/a> e ti rendi conto di non poter ancora accedere alle tue funzionalit\u00e0 premium, allora sei nel posto giusto. In questa guida, ti mostrer\u00f2 come risolvere il problema. <\/p>\n\n<h2 class=\"wp-block-heading\">Conferma il tuo acquisto<\/h2>\n\n<p class=\"wp-block-paragraph\">Per prima cosa, verifica se l&#8217;acquisto \u00e8 andato a buon fine controllando la tua casella di posta. Dovresti trovare una ricevuta che attesta che il pagamento \u00e8 stato ricevuto e che il tuo abbonamento \u00e8 ora attivo. <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\">Esci e accedi di nuovo<\/h2>\n\n<p class=\"wp-block-paragraph\">Occasionalmente, l&#8217;account Klangio ha difficolt\u00e0 a registrare le modifiche. Per risolvere questo problema, \u00e8 sufficiente <a href=\"\/?knowledge_base=create-account\" target=\"_blank\" rel=\"noreferrer noopener\">disconnettersi e accedere di nuovo al tuo account<\/a>. <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\">Controlla lo stato del tuo account<\/h2>\n\n<p class=\"wp-block-paragraph\">Puoi verificare se l&#8217;abbonamento \u00e8 attivato con l&#8217;account Klangio con cui hai effettuato l&#8217;accesso:<\/p>\n\n<ol class=\"wp-block-list\">\n<li>Vai al tuo songbook.<\/li>\n\n\n\n<li>Apri il menu nell&#8217;angolo in alto a destra.<\/li>\n\n\n\n<li>Clicca su \u201cInformazioni account\u201d<\/li>\n\n\n\n<li>Verifica se il tuo abbonamento \u00e8 menzionato in questa sezione.<\/li>\n<\/ol>\n\n<p class=\"wp-block-paragraph\">Se il tuo abbonamento non \u00e8 menzionato, potrebbe anche essere che tu non abbia effettuato l&#8217;accesso all&#8217;account per il quale hai acquistato l&#8217;abbonamento. Controlla la ricevuta che hai ricevuto via e-mail per assicurarti che l&#8217;acquisto sia andato a buon fine e che tu stia utilizzando l&#8217;account e l&#8217;indirizzo e-mail corretti. <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\">Assicurati di utilizzare l&#8217;app Klangio corretta<\/h2>\n\n<p class=\"wp-block-paragraph\">Pu\u00f2 succedere che tu abbia accidentalmente navigato verso un&#8217;app Klangio diversa dall&#8217;abbonamento Klangio che hai acquistato. In questo caso, prova questo: <\/p>\n\n<ol class=\"wp-block-list\">\n<li>Conferma quale abbonamento Klangio hai acquistato (ad esempio Piano2Notes Pro, Scan2Notes Pro, Klangio Universe) con la ricevuta che hai ricevuto via e-mail dopo l&#8217;acquisto. Assicurati inoltre che non ci siano errori di battitura nell&#8217;e-mail per la quale hai acquistato l&#8217;abbonamento. <\/li>\n\n\n\n<li>Vai su klang.io e clicca sulla sezione &#8220;Prodotti&#8221; nella parte superiore dello schermo. Seleziona l&#8217;app per la quale hai acquistato un abbonamento. <\/li>\n\n\n\n<li>Clicca sul pulsante &#8220;Accedi&#8221; nell&#8217;angolo in alto a destra oppure apri il menu nell&#8217;angolo in alto a destra e clicca su &#8220;Accedi&#8221; se stai utilizzando il tuo smartphone.<\/li>\n\n\n\n<li>Assicurati di utilizzare l&#8217;indirizzo e-mail dell&#8217;account Klangio, che hai utilizzato anche per l&#8217;acquisto dell&#8217;abbonamento.<\/li>\n<\/ol>\n\n<h2 class=\"wp-block-heading\">Contattaci!<\/h2>\n\n<p class=\"wp-block-paragraph\">Nel caso in cui tu non abbia ancora accesso alle tue funzionalit\u00e0 premium o al tuo account, attendi un&#8217;ora e riprova. Se anche questo non dovesse funzionare, contattaci tramite il nostro <a href=\"https:\/\/klang.io\/it\/about-us\/contact\/\" target=\"_blank\" rel=\"noreferrer noopener\">modulo di contatto<\/a> e fai sapere al nostro chatbot che hai gi\u00e0 provato tutti questi passaggi e che vorresti parlare con un membro del nostro team di supporto. <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Spero che questo spieghi come attivare il tuo abbonamento a Klangio, se non lo fa automaticamente.<br\/><\/p>\n\n<p class=\"wp-block-paragraph\">Sentiti libero di consultare gli altri articoli nel nostro <a href=\"https:\/\/klang.io\/help\" target=\"_blank\" rel=\"noreferrer noopener\">Centro assistenza<\/a>, se hai domande sul tuo abbonamento a Klangio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se hai appena effettuato l&#8217;upgrade al nostro abbonamento Pro per una qualsiasi delle app Klangio e ti rendi conto di non poter ancora accedere alle tue funzionalit\u00e0 premium, allora sei nel posto giusto. In questa guida, ti mostrer\u00f2 come risolvere il problema. Conferma il tuo acquisto Per prima cosa, verifica se l&#8217;acquisto \u00e8 andato a [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"doc_category":[462],"doc_tag":[],"knowledge_base":[467,465,520,468,497,464,469,466],"class_list":["post-32291","docs","type-docs","status-publish","hentry","doc_category-abbonamenti","knowledge_base-drum2notes-it","knowledge_base-guitar2tabs-it","knowledge_base-klangio-transcription-plugin-it","knowledge_base-klangio-transcription-studio-it","knowledge_base-melody-scanner-it","knowledge_base-piano2notes-it","knowledge_base-scan2notes-it","knowledge_base-sing2notes-it"],"year_month":"2026-07","word_count":429,"total_views":"433","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"Christoph Zimmer","author_nicename":"chris","author_url":"https:\/\/klang.io\/it\/blog\/author\/chris\/"},"doc_category_info":[{"term_name":"Abbonamenti","term_url":"https:\/\/klang.io\/it\/help\/non-knowledgebase\/abbonamenti\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Il mio abbonamento a Klangio non \u00e8 attivo | klang.io<\/title>\n<meta name=\"description\" content=\"Scopri come attivare il tuo abbonamento a Klangio nel caso in cui riscontrassi problemi dopo l&#039;acquisto. Segui semplicemente la guida.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/klang.io\/it\/help\/subscription-not-active\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il mio abbonamento a Klangio non \u00e8 attivo | klang.io\" \/>\n<meta property=\"og:description\" content=\"Scopri come attivare il tuo abbonamento a Klangio nel caso in cui riscontrassi problemi dopo l&#039;acquisto. Segui semplicemente la guida.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/klang.io\/it\/help\/subscription-not-active\/\" \/>\n<meta property=\"og:site_name\" content=\"klang.io\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/klangio\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-08T05:17:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@klangio\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/klang.io\/it\/help\/subscription-not-active\/\",\"url\":\"https:\/\/klang.io\/it\/help\/subscription-not-active\/\",\"name\":\"Il mio abbonamento a Klangio non \u00e8 attivo | klang.io\",\"isPartOf\":{\"@id\":\"https:\/\/klang.io\/it\/#website\"},\"datePublished\":\"2024-05-22T09:36:19+00:00\",\"dateModified\":\"2025-09-08T05:17:53+00:00\",\"description\":\"Scopri come attivare il tuo abbonamento a Klangio nel caso in cui riscontrassi problemi dopo l'acquisto. Segui semplicemente la guida.\",\"breadcrumb\":{\"@id\":\"https:\/\/klang.io\/it\/help\/subscription-not-active\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/klang.io\/it\/help\/subscription-not-active\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/klang.io\/it\/help\/subscription-not-active\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/klang.io\/it\/home-2\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Help Center\",\"item\":\"https:\/\/klang.io\/it\/help\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Il mio abbonamento a Klangio non \u00e8 attivo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/klang.io\/it\/#website\",\"url\":\"https:\/\/klang.io\/it\/\",\"name\":\"Klangio\",\"description\":\"AI Tools for Musicians\",\"publisher\":{\"@id\":\"https:\/\/klang.io\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/klang.io\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/klang.io\/it\/#organization\",\"name\":\"Klangio GmbH\",\"url\":\"https:\/\/klang.io\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/klang.io\/it\/#\/schema\/logo\/image\/\",\"url\":\"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png\",\"contentUrl\":\"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png\",\"width\":512,\"height\":512,\"caption\":\"Klangio GmbH\"},\"image\":{\"@id\":\"https:\/\/klang.io\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/klangio\",\"https:\/\/x.com\/klangio\",\"https:\/\/www.linkedin.com\/company\/klangio\/\",\"https:\/\/www.instagram.com\/klangio\/\",\"https:\/\/www.youtube.com\/@Klangio\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il mio abbonamento a Klangio non \u00e8 attivo | klang.io","description":"Scopri come attivare il tuo abbonamento a Klangio nel caso in cui riscontrassi problemi dopo l'acquisto. Segui semplicemente la guida.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/klang.io\/it\/help\/subscription-not-active\/","og_locale":"it_IT","og_type":"article","og_title":"Il mio abbonamento a Klangio non \u00e8 attivo | klang.io","og_description":"Scopri come attivare il tuo abbonamento a Klangio nel caso in cui riscontrassi problemi dopo l'acquisto. Segui semplicemente la guida.","og_url":"https:\/\/klang.io\/it\/help\/subscription-not-active\/","og_site_name":"klang.io","article_publisher":"https:\/\/facebook.com\/klangio","article_modified_time":"2025-09-08T05:17:53+00:00","twitter_card":"summary_large_image","twitter_site":"@klangio","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/klang.io\/it\/help\/subscription-not-active\/","url":"https:\/\/klang.io\/it\/help\/subscription-not-active\/","name":"Il mio abbonamento a Klangio non \u00e8 attivo | klang.io","isPartOf":{"@id":"https:\/\/klang.io\/it\/#website"},"datePublished":"2024-05-22T09:36:19+00:00","dateModified":"2025-09-08T05:17:53+00:00","description":"Scopri come attivare il tuo abbonamento a Klangio nel caso in cui riscontrassi problemi dopo l'acquisto. Segui semplicemente la guida.","breadcrumb":{"@id":"https:\/\/klang.io\/it\/help\/subscription-not-active\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/klang.io\/it\/help\/subscription-not-active\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/klang.io\/it\/help\/subscription-not-active\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/klang.io\/it\/home-2\/"},{"@type":"ListItem","position":2,"name":"Help Center","item":"https:\/\/klang.io\/it\/help\/"},{"@type":"ListItem","position":3,"name":"Il mio abbonamento a Klangio non \u00e8 attivo"}]},{"@type":"WebSite","@id":"https:\/\/klang.io\/it\/#website","url":"https:\/\/klang.io\/it\/","name":"Klangio","description":"AI Tools for Musicians","publisher":{"@id":"https:\/\/klang.io\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/klang.io\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/klang.io\/it\/#organization","name":"Klangio GmbH","url":"https:\/\/klang.io\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/klang.io\/it\/#\/schema\/logo\/image\/","url":"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png","contentUrl":"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png","width":512,"height":512,"caption":"Klangio GmbH"},"image":{"@id":"https:\/\/klang.io\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/klangio","https:\/\/x.com\/klangio","https:\/\/www.linkedin.com\/company\/klangio\/","https:\/\/www.instagram.com\/klangio\/","https:\/\/www.youtube.com\/@Klangio"]}]}},"knowledge_base_info":[{"term_name":"Drum2Notes","term_url":"https:\/\/klang.io\/it\/help\/drum2notes-it\/","term_slug":"drum2notes-it"},{"term_name":"Guitar2Tabs","term_url":"https:\/\/klang.io\/it\/help\/guitar2tabs-it\/","term_slug":"guitar2tabs-it"},{"term_name":"Klangio Transcription Plugin","term_url":"https:\/\/klang.io\/it\/help\/klangio-transcription-plugin-it\/","term_slug":"klangio-transcription-plugin-it"},{"term_name":"Klangio Transcription Studio","term_url":"https:\/\/klang.io\/it\/help\/klangio-transcription-studio-it\/","term_slug":"klangio-transcription-studio-it"},{"term_name":"Melody Scanner","term_url":"https:\/\/klang.io\/it\/help\/melody-scanner-it\/","term_slug":"melody-scanner-it"},{"term_name":"Piano2Notes","term_url":"https:\/\/klang.io\/it\/help\/piano2notes-it\/","term_slug":"piano2notes-it"},{"term_name":"Scan2Notes","term_url":"https:\/\/klang.io\/it\/help\/scan2notes-it\/","term_slug":"scan2notes-it"},{"term_name":"Sing2Notes","term_url":"https:\/\/klang.io\/it\/help\/sing2notes-it\/","term_slug":"sing2notes-it"}],"knowledge_base_slug":["drum2notes-it","guitar2tabs-it","klangio-transcription-plugin-it","klangio-transcription-studio-it","melody-scanner-it","piano2notes-it","scan2notes-it","sing2notes-it"],"_links":{"self":[{"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/docs\/32291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/comments?post=32291"}],"version-history":[{"count":2,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/docs\/32291\/revisions"}],"predecessor-version":[{"id":38612,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/docs\/32291\/revisions\/38612"}],"wp:attachment":[{"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/media?parent=32291"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/doc_category?post=32291"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/doc_tag?post=32291"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/knowledge_base?post=32291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}