{"id":32317,"date":"2024-05-15T08:35:40","date_gmt":"2024-05-15T08:35:40","guid":{"rendered":"https:\/\/klang.io\/help\/transcribing-takes-long\/"},"modified":"2025-07-17T09:59:33","modified_gmt":"2025-07-17T09:59:33","password":"","slug":"transcribing-takes-long","status":"publish","type":"docs","link":"https:\/\/klang.io\/it\/help\/transcribing-takes-long\/","title":{"rendered":"La trascrizione richiede insolitamente molto tempo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Se hai notato che il processo di trascrizione con una delle app <a href=\"https:\/\/klang.io\/it\/\" target=\"_blank\" rel=\"noreferrer noopener\">Klangio<\/a> richiede un tempo insolitamente lungo, questo articolo pu\u00f2 esserti d&#8217;aiuto.<\/p>\n\n<h2 class=\"wp-block-heading\">Aggiorna il sito web \/ riavvia l&#8217;app<\/h2>\n\n<p class=\"wp-block-paragraph\">Una delle soluzioni pi\u00f9 semplici da provare \u00e8 aggiornare il sito web o riavviare l&#8217;app, quindi riprovare.<\/p>\n\n<h2 class=\"wp-block-heading\">Problemi di rete o di connettivit\u00e0<\/h2>\n\n<p class=\"wp-block-paragraph\">Una connessione insufficiente ai nostri server pu\u00f2 essere una delle cause di un lungo tempo di attesa. In particolare, il caricamento dei file pu\u00f2 richiedere molto tempo in questo caso. Sentiti libero di provare a <a href=\"\/?knowledge_base=audio-youtube-into-sheet\" target=\"_blank\" rel=\"noreferrer noopener\">incollare un link di YouTube invece di caricare un file<\/a> o viceversa, per verificare se una di queste opzioni funziona meglio. Se non funziona nulla, devi accedere a una rete con una connessione Internet migliore.   <\/p>\n\n<h2 class=\"wp-block-heading\">Elevata domanda o manutenzione del server<\/h2>\n\n<p class=\"wp-block-paragraph\">Occasionalmente, molte persone vogliono trascrivere contemporaneamente. Anche se controlliamo costantemente le capacit\u00e0 dei server, si verificano picchi imprevisti che devono essere elaborati lentamente e costantemente. I nostri server devono anche essere sottoposti a manutenzione di tanto in tanto, il che pu\u00f2 anche ridurre la velocit\u00e0 di trascrizione. In questi casi, sii paziente e riprova tra qualche ora o il giorno successivo. Grazie per la comprensione \ud83d\ude42    <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Sentiti libero di consultare gli altri articoli nel nostro <a href=\"https:\/\/klang.io\/help\">Centro assistenza<\/a>, se hai domande sul perch\u00e9 la tua trascrizione potrebbe richiedere un po&#8217; pi\u00f9 di tempo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se hai notato che il processo di trascrizione con una delle app Klangio richiede un tempo insolitamente lungo, questo articolo pu\u00f2 esserti d&#8217;aiuto. Aggiorna il sito web \/ riavvia l&#8217;app Una delle soluzioni pi\u00f9 semplici da provare \u00e8 aggiornare il sito web o riavviare l&#8217;app, quindi riprovare. Problemi di rete o di connettivit\u00e0 Una connessione [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"doc_category":[523],"doc_tag":[],"knowledge_base":[467,465,468,497,464,469,466],"class_list":["post-32317","docs","type-docs","status-publish","hentry","doc_category-risoluzione-dei-problemi","knowledge_base-drum2notes-it","knowledge_base-guitar2tabs-it","knowledge_base-klangio-transcription-studio-it","knowledge_base-melody-scanner-it","knowledge_base-piano2notes-it","knowledge_base-scan2notes-it","knowledge_base-sing2notes-it"],"year_month":"2026-07","word_count":218,"total_views":"453","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"Christoph Zimmer","author_nicename":"chris","author_url":"https:\/\/klang.io\/it\/blog\/author\/chris\/"},"doc_category_info":[{"term_name":"Risoluzione dei problemi","term_url":"https:\/\/klang.io\/it\/help\/non-knowledgebase\/risoluzione-dei-problemi\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La trascrizione richiede insolitamente molto tempo | klang.io<\/title>\n<meta name=\"description\" content=\"Scopri perch\u00e9 la tua trascrizione potrebbe richiedere un tempo insolitamente lungo e quali sono le cause e le soluzioni.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/klang.io\/it\/help\/transcribing-takes-long\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La trascrizione richiede insolitamente molto tempo | klang.io\" \/>\n<meta property=\"og:description\" content=\"Scopri perch\u00e9 la tua trascrizione potrebbe richiedere un tempo insolitamente lungo e quali sono le cause e le soluzioni.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/klang.io\/it\/help\/transcribing-takes-long\/\" \/>\n<meta property=\"og:site_name\" content=\"klang.io\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/klangio\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-17T09:59:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@klangio\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/klang.io\/it\/help\/transcribing-takes-long\/\",\"url\":\"https:\/\/klang.io\/it\/help\/transcribing-takes-long\/\",\"name\":\"La trascrizione richiede insolitamente molto tempo | klang.io\",\"isPartOf\":{\"@id\":\"https:\/\/klang.io\/it\/#website\"},\"datePublished\":\"2024-05-15T08:35:40+00:00\",\"dateModified\":\"2025-07-17T09:59:33+00:00\",\"description\":\"Scopri perch\u00e9 la tua trascrizione potrebbe richiedere un tempo insolitamente lungo e quali sono le cause e le soluzioni.\",\"breadcrumb\":{\"@id\":\"https:\/\/klang.io\/it\/help\/transcribing-takes-long\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/klang.io\/it\/help\/transcribing-takes-long\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/klang.io\/it\/help\/transcribing-takes-long\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/klang.io\/it\/home-2\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Help Center\",\"item\":\"https:\/\/klang.io\/it\/help\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La trascrizione richiede insolitamente molto tempo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/klang.io\/it\/#website\",\"url\":\"https:\/\/klang.io\/it\/\",\"name\":\"Klangio\",\"description\":\"AI Tools for Musicians\",\"publisher\":{\"@id\":\"https:\/\/klang.io\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/klang.io\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/klang.io\/it\/#organization\",\"name\":\"Klangio GmbH\",\"url\":\"https:\/\/klang.io\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/klang.io\/it\/#\/schema\/logo\/image\/\",\"url\":\"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png\",\"contentUrl\":\"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png\",\"width\":512,\"height\":512,\"caption\":\"Klangio GmbH\"},\"image\":{\"@id\":\"https:\/\/klang.io\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/klangio\",\"https:\/\/x.com\/klangio\",\"https:\/\/www.linkedin.com\/company\/klangio\/\",\"https:\/\/www.instagram.com\/klangio\/\",\"https:\/\/www.youtube.com\/@Klangio\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La trascrizione richiede insolitamente molto tempo | klang.io","description":"Scopri perch\u00e9 la tua trascrizione potrebbe richiedere un tempo insolitamente lungo e quali sono le cause e le soluzioni.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/klang.io\/it\/help\/transcribing-takes-long\/","og_locale":"it_IT","og_type":"article","og_title":"La trascrizione richiede insolitamente molto tempo | klang.io","og_description":"Scopri perch\u00e9 la tua trascrizione potrebbe richiedere un tempo insolitamente lungo e quali sono le cause e le soluzioni.","og_url":"https:\/\/klang.io\/it\/help\/transcribing-takes-long\/","og_site_name":"klang.io","article_publisher":"https:\/\/facebook.com\/klangio","article_modified_time":"2025-07-17T09:59:33+00:00","twitter_card":"summary_large_image","twitter_site":"@klangio","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/klang.io\/it\/help\/transcribing-takes-long\/","url":"https:\/\/klang.io\/it\/help\/transcribing-takes-long\/","name":"La trascrizione richiede insolitamente molto tempo | klang.io","isPartOf":{"@id":"https:\/\/klang.io\/it\/#website"},"datePublished":"2024-05-15T08:35:40+00:00","dateModified":"2025-07-17T09:59:33+00:00","description":"Scopri perch\u00e9 la tua trascrizione potrebbe richiedere un tempo insolitamente lungo e quali sono le cause e le soluzioni.","breadcrumb":{"@id":"https:\/\/klang.io\/it\/help\/transcribing-takes-long\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/klang.io\/it\/help\/transcribing-takes-long\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/klang.io\/it\/help\/transcribing-takes-long\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/klang.io\/it\/home-2\/"},{"@type":"ListItem","position":2,"name":"Help Center","item":"https:\/\/klang.io\/it\/help\/"},{"@type":"ListItem","position":3,"name":"La trascrizione richiede insolitamente molto tempo"}]},{"@type":"WebSite","@id":"https:\/\/klang.io\/it\/#website","url":"https:\/\/klang.io\/it\/","name":"Klangio","description":"AI Tools for Musicians","publisher":{"@id":"https:\/\/klang.io\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/klang.io\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/klang.io\/it\/#organization","name":"Klangio GmbH","url":"https:\/\/klang.io\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/klang.io\/it\/#\/schema\/logo\/image\/","url":"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png","contentUrl":"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png","width":512,"height":512,"caption":"Klangio GmbH"},"image":{"@id":"https:\/\/klang.io\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/klangio","https:\/\/x.com\/klangio","https:\/\/www.linkedin.com\/company\/klangio\/","https:\/\/www.instagram.com\/klangio\/","https:\/\/www.youtube.com\/@Klangio"]}]}},"knowledge_base_info":[{"term_name":"Drum2Notes","term_url":"https:\/\/klang.io\/it\/help\/drum2notes-it\/","term_slug":"drum2notes-it"},{"term_name":"Guitar2Tabs","term_url":"https:\/\/klang.io\/it\/help\/guitar2tabs-it\/","term_slug":"guitar2tabs-it"},{"term_name":"Klangio Transcription Studio","term_url":"https:\/\/klang.io\/it\/help\/klangio-transcription-studio-it\/","term_slug":"klangio-transcription-studio-it"},{"term_name":"Melody Scanner","term_url":"https:\/\/klang.io\/it\/help\/melody-scanner-it\/","term_slug":"melody-scanner-it"},{"term_name":"Piano2Notes","term_url":"https:\/\/klang.io\/it\/help\/piano2notes-it\/","term_slug":"piano2notes-it"},{"term_name":"Scan2Notes","term_url":"https:\/\/klang.io\/it\/help\/scan2notes-it\/","term_slug":"scan2notes-it"},{"term_name":"Sing2Notes","term_url":"https:\/\/klang.io\/it\/help\/sing2notes-it\/","term_slug":"sing2notes-it"}],"knowledge_base_slug":["drum2notes-it","guitar2tabs-it","klangio-transcription-studio-it","melody-scanner-it","piano2notes-it","scan2notes-it","sing2notes-it"],"_links":{"self":[{"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/docs\/32317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/comments?post=32317"}],"version-history":[{"count":0,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/docs\/32317\/revisions"}],"wp:attachment":[{"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/media?parent=32317"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/doc_category?post=32317"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/doc_tag?post=32317"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/knowledge_base?post=32317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}