{"id":32380,"date":"2024-09-09T14:12:02","date_gmt":"2024-09-09T14:12:02","guid":{"rendered":"https:\/\/klang.io\/help\/transcription-wizard\/"},"modified":"2025-12-01T06:18:47","modified_gmt":"2025-12-01T06:18:47","password":"","slug":"transcription-wizard","status":"publish","type":"docs","link":"https:\/\/klang.io\/it\/help\/transcription-wizard\/","title":{"rendered":"Come utilizzare la procedura guidata di Klangio Transcription"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">In questa guida, ti mostrer\u00f2 come utilizzare la procedura guidata di <a href=\"https:\/\/klang.io\/it\/\" target=\"_blank\" rel=\"noreferrer noopener\">Klangio<\/a> Transcription, che rende la trascrizione cos\u00ec facile che sembra magia!<\/p>\n\n<p class=\"wp-block-paragraph\">Guarda il video e continua a leggere per saperne di pi\u00f9:<\/p>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Turn Full Songs into Notes AUTOMATICALLY | Transcription Wizard Update - Klangio\" width=\"800\" height=\"450\" data-src=\"https:\/\/www.youtube.com\/embed\/sYjdKG87c2o?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe>\n<\/div><\/figure>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\">Apertura della procedura guidata di trascrizione<\/h2>\n\n<p class=\"wp-block-paragraph\">La nuova procedura guidata di Transcription si aprir\u00e0 automaticamente una volta che <a href=\"\/?doc_category=audio-youtube-into-sheet\" target=\"_blank\" rel=\"noreferrer noopener\">avvierai una nuova trascrizione<\/a>. Vai semplicemente a una delle nostre app e inizia gratuitamente!<\/p>\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/klang.io\/it\/piano2notes\/\" target=\"_blank\" rel=\"noreferrer noopener\">Piano2Notes<\/a>: trascrivi pianoforti<\/li>\n\n\n\n<li><a href=\"https:\/\/klang.io\/it\/guitar2tabs\/\" target=\"_blank\" rel=\"noreferrer noopener\">Guitar2Tabs<\/a>: trascrivi chitarre elettriche, acustiche e bassi<\/li>\n\n\n\n<li><a href=\"https:\/\/klang.io\/it\/sing2notes\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sing2Notes<\/a>: trascrivi voci e canto<\/li>\n\n\n\n<li><a href=\"https:\/\/klang.io(drum2notes\" target=\"_blank\" rel=\"noreferrer noopener\">Drum2Notes<\/a>: trascrivi batterie<\/li>\n\n\n\n<li><a href=\"https:\/\/klang.io\/it\/transcription-studio\/\" target=\"_blank\" rel=\"noreferrer noopener\">Klangio Transcription Studio<\/a>: trascrivi pi\u00f9 strumenti contemporaneamente<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/klang.io\/it\/scan2notes\/\" target=\"_blank\" rel=\"noreferrer noopener\">Scan2Notes<\/a> non trascrive, ma scansiona la tua musica stampata caricata. Puoi trovare un tutorial specifico su come utilizzare Scan2Notes qui. <\/p>\n\n<h2 class=\"wp-block-heading\">Passaggio 1: scelta di uno strumento<\/h2>\n\n<p class=\"wp-block-paragraph\">Innanzitutto, la procedura guidata di trascrizione ti chieder\u00e0 di scegliere lo strumento che desideri trascrivere. Ogni app copre il proprio set di strumenti. Tieni presente che \u00e8 possibile trascrivere un solo strumento alla volta.  <\/p>\n\n<figure class=\"wp-block-image aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"724\" height=\"330\" src=\"\/wp-content\/uploads\/2024\/09\/image.png\" alt=\"Piano2Notes: scegli lo strumento che desideri trascrivere.\" class=\"wp-image-22600\" srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/image.png 724w, https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/image-300x137.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/image-360x164.png 360w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/><figcaption class=\"wp-element-caption\">Piano2Notes: scegli lo strumento che desideri trascrivere.<\/figcaption><\/figure>\n\n<h2 class=\"wp-block-heading\">Passaggio 2: registrazione di pi\u00f9 strumenti o assolo<\/h2>\n\n<p class=\"wp-block-paragraph\">Successivamente, scegli se il brano che hai caricato contiene solo lo strumento che hai selezionato nel passaggio precedente (fai clic su \u201cRegistrazione assolo\u201d) oppure, se ci sono altri strumenti udibili nel brano (fai clic su \u201cPi\u00f9 strumenti\u201d). <\/p>\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"724\" height=\"312\" data-src=\"\/wp-content\/uploads\/2024\/09\/image-1.png\" alt=\"Piano2Notes: scegli Registrazione assolo o Pi&#xF9; strumenti\" class=\"wp-image-22608 lazyload\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/image-1.png 724w, https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/image-1-300x129.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/image-1-360x155.png 360w\" data-sizes=\"(max-width: 724px) 100vw, 724px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 724px; --smush-placeholder-aspect-ratio: 724\/312;\" \/><figcaption class=\"wp-element-caption\">Piano2Notes: scegli Registrazione assolo o Pi\u00f9 strumenti<\/figcaption><\/figure>\n\n<h3 class=\"wp-block-heading\">Passaggio 2.5: impostazioni specifiche per la registrazione assolo<\/h3>\n\n<p class=\"wp-block-paragraph\">Se hai selezionato \u201cRegistrazione assolo\u201d nel passaggio precedente, ti verr\u00e0 presentato un altro passaggio specifico dell&#8217;app:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Piano2Notes: abilita i contrassegni del pedale.<\/li>\n\n\n\n<li>Guitar2Tabs: scegli la modalit\u00e0 Picking o Strumming.<\/li>\n\n\n\n<li>Sing2Notes &amp; Drum2Notes: nessun passaggio aggiuntivo.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\">Passaggio 3: impostazioni specifiche obbligatorie dell&#8217;app<\/h2>\n\n<p class=\"wp-block-paragraph\">Ogni app ti presenter\u00e0 ora ulteriori impostazioni in base allo strumento che hai selezionato:<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Piano2Notes &amp; Klangio Transcription Studio: scegli lo stile della canzone (Pop o Classica) e le impostazioni del pedale<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">Se stai trascrivendo un pianoforte come strumento solista, hai la possibilit\u00e0 di scegliere se visualizzare i contrassegni del pedale sul tuo spartito e se la musica che hai caricato \u00e8 pi\u00f9 in linea con la musica pop o classica.<\/p>\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" width=\"723\" height=\"267\" data-src=\"\/wp-content\/uploads\/2024\/09\/image-6.png\" alt=\"\" class=\"wp-image-29602 lazyload\" style=\"--smush-placeholder-width: 723px; --smush-placeholder-aspect-ratio: 723\/267;width:557px;height:auto\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/image-6.png 723w, https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/image-6-300x111.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/image-6-360x133.png 360w\" data-sizes=\"(max-width: 723px) 100vw, 723px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">Piano2Notes: scegli se visualizzare i contrassegni del pedale.<\/figcaption><\/figure>\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" width=\"727\" height=\"299\" data-src=\"\/wp-content\/uploads\/2024\/09\/image-2.png\" alt=\"Piano2Notes: scegli lo stile del brano.\" class=\"wp-image-22632 lazyload\" style=\"--smush-placeholder-width: 727px; --smush-placeholder-aspect-ratio: 727\/299;width:531px;height:auto\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/image-2.png 727w, https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/image-2-300x123.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/image-2-360x148.png 360w\" data-sizes=\"(max-width: 727px) 100vw, 727px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">Piano2Notes: scegli lo stile del brano.<\/figcaption><\/figure>\n\n<h3 class=\"wp-block-heading\"><strong>Guitar2Tabs &amp; Klangio Transcription Studio: scegli l&#8217;accordatura e il capotasto.<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">Se stai trascrivendo una chitarra come strumento solista, puoi scegliere di aggiungere un capotasto alla tua trascrizione e modificare l&#8217;accordatura.<\/p>\n\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-f56f9fcf wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"745\" height=\"423\" data-src=\"\/wp-content\/uploads\/2024\/09\/Screenshot-2024-09-10-123158.jpg\" alt=\"Guitar2Tabs: seleziona un'accordatura.\" class=\"wp-image-22616 lazyload\" style=\"--smush-placeholder-width: 745px; --smush-placeholder-aspect-ratio: 745\/423;width:318px;height:auto\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/Screenshot-2024-09-10-123158.jpg 745w, https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/Screenshot-2024-09-10-123158-300x170.jpg 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/Screenshot-2024-09-10-123158-360x204.jpg 360w\" data-sizes=\"(max-width: 745px) 100vw, 745px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">Guitar2Tabs: seleziona un&#8217;accordatura.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"740\" height=\"309\" data-src=\"\/wp-content\/uploads\/2024\/09\/Screenshot-2024-09-10-123218.jpg\" alt=\"Guitar2Tabs: abilita il capotasto.\" class=\"wp-image-22624 lazyload\" style=\"--smush-placeholder-width: 740px; --smush-placeholder-aspect-ratio: 740\/309;width:434px;height:auto\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/Screenshot-2024-09-10-123218.jpg 740w, https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/Screenshot-2024-09-10-123218-300x125.jpg 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/Screenshot-2024-09-10-123218-360x150.jpg 360w\" data-sizes=\"(max-width: 740px) 100vw, 740px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">Guitar2Tabs: abilita il capotasto.<\/figcaption><\/figure>\n<\/div>\n\n<h3 class=\"wp-block-heading\"><strong>Drum2Notes &amp; Klangio Transcription Studio: scegli il set di batteria e piatti<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">Se stai trascrivendo la batteria come strumento solista, puoi scegliere di semplificare la trascrizione del tuo set di batteria.<\/p>\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" width=\"728\" height=\"334\" data-src=\"\/wp-content\/uploads\/2024\/09\/image-3.png\" alt=\"Drum2Notes: seleziona il set di batteria.\" class=\"wp-image-22640 lazyload\" style=\"--smush-placeholder-width: 728px; --smush-placeholder-aspect-ratio: 728\/334;width:636px;height:auto\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/image-3.png 728w, https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/image-3-300x138.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/image-3-360x165.png 360w\" data-sizes=\"(max-width: 728px) 100vw, 728px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">Drum2Notes: seleziona la complessit\u00e0 del set di batteria.<\/figcaption><\/figure>\n\n<h3 class=\"wp-block-heading\"><strong>Sing2Notes &amp; Klangio Transcription Studio: scegli di aggiungere i testi.<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">Quando la tua trascrizione contiene voci, puoi scegliere di utilizzare i testi rilevati automaticamente nel tuo spartito.<\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"892\" height=\"344\" data-src=\"\/wp-content\/uploads\/2024\/09\/image-7.png\" alt=\"\" class=\"wp-image-29610 lazyload\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/image-7.png 892w, https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/image-7-300x116.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/image-7-768x296.png 768w, https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/image-7-360x139.png 360w\" data-sizes=\"(max-width: 892px) 100vw, 892px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 892px; --smush-placeholder-aspect-ratio: 892\/344;\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\">Passaggio 4: informazioni aggiuntive o modalit\u00e0 automatica<\/h2>\n\n<p class=\"wp-block-paragraph\">Successivamente, puoi scegliere di aggiungere informazioni aggiuntive alla tua trascrizione, il che pu\u00f2 migliorare la qualit\u00e0 delle note che verranno generate. <a href=\"\/?doc_category=additional-information\">Leggi di pi\u00f9 qui.<\/a> Se non sei sicuro, puoi lasciare che Klangio applichi le impostazioni per te.<\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"726\" height=\"328\" data-src=\"\/wp-content\/uploads\/2024\/09\/image-4.png\" alt=\"Piano2Notes: aggiungi informazioni aggiuntive o avvia una trascrizione automatica.\" class=\"wp-image-22648 lazyload\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/image-4.png 726w, https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/image-4-300x136.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/image-4-360x163.png 360w\" data-sizes=\"(max-width: 726px) 100vw, 726px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 726px; --smush-placeholder-aspect-ratio: 726\/328;\" \/><figcaption class=\"wp-element-caption\">Piano2Notes: aggiungi informazioni aggiuntive o avvia una trascrizione automatica.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\">Passaggio 5: avvia la trascrizione<\/h2>\n\n<p class=\"wp-block-paragraph\">Infine, aggiungi il titolo e il compositore del brano e accetta i termini e le condizioni. Puoi quindi avviare <a href=\"\/?doc_category=difference-demo-full\" target=\"_blank\" rel=\"noreferrer noopener\">una trascrizione completa o una trascrizione demo gratuita<\/a>. <\/p>\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"729\" height=\"492\" data-src=\"\/wp-content\/uploads\/2024\/09\/image-5.png\" alt=\"Piano2Notes: aggiungi il nome e il compositore e avvia la trascrizione.\" class=\"wp-image-22656 lazyload\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/image-5.png 729w, https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/image-5-300x202.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/image-5-360x243.png 360w\" data-sizes=\"(max-width: 729px) 100vw, 729px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 729px; --smush-placeholder-aspect-ratio: 729\/492;\" \/><figcaption class=\"wp-element-caption\">Piano2Notes: aggiungi il nome e il compositore e avvia la trascrizione.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Sentiti libero di consultare gli altri articoli nel nostro <a href=\"https:\/\/klang.io\/help\" target=\"_blank\" rel=\"noreferrer noopener\">Centro Aiuto<\/a>, se hai domande sulla procedura guidata di Transcription di Klangio.<\/p>\n\n<h2 class=\"wp-block-heading\">Domande frequenti<\/h2>\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1764079700976\"><strong class=\"schema-faq-question\">Klangio \u00e8 in grado di rilevare quali strumenti vengono suonati in una canzone o registrazione?<\/strong> <p class=\"schema-faq-answer\">S\u00ec. Nella procedura guidata di trascrizione, seleziona &#8220;Rileva automaticamente gli strumenti&#8221; dopo aver avviato una trascrizione. <\/p> <\/div> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>In questa guida, ti mostrer\u00f2 come utilizzare la procedura guidata di Klangio Transcription, che rende la trascrizione cos\u00ec facile che sembra magia! Guarda il video e continua a leggere per saperne di pi\u00f9: Apertura della procedura guidata di trascrizione La nuova procedura guidata di Transcription si aprir\u00e0 automaticamente una volta che avvierai una nuova trascrizione. [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":22667,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"doc_category":[463],"doc_tag":[],"knowledge_base":[467,465,468,464,469,466],"class_list":["post-32380","docs","type-docs","status-publish","has-post-thumbnail","hentry","doc_category-trascrizione","knowledge_base-drum2notes-it","knowledge_base-guitar2tabs-it","knowledge_base-klangio-transcription-studio-it","knowledge_base-piano2notes-it","knowledge_base-scan2notes-it","knowledge_base-sing2notes-it"],"year_month":"2026-07","word_count":617,"total_views":"598","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"Christoph Zimmer","author_nicename":"chris","author_url":"https:\/\/klang.io\/it\/blog\/author\/chris\/"},"doc_category_info":[{"term_name":"Trascrizione","term_url":"https:\/\/klang.io\/it\/help\/non-knowledgebase\/trascrizione\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Come utilizzare la procedura guidata di Klangio Transcription | klang.io<\/title>\n<meta name=\"description\" content=\"La procedura guidata di Klangio Transcription rende la trascrizione musicale cos\u00ec facile che sembra magia! Leggi questa guida per saperne di pi\u00f9 sulle impostazioni.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/klang.io\/it\/help\/transcription-wizard\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come utilizzare la procedura guidata di Klangio Transcription | klang.io\" \/>\n<meta property=\"og:description\" content=\"La procedura guidata di Klangio Transcription rende la trascrizione musicale cos\u00ec facile che sembra magia! Leggi questa guida per saperne di pi\u00f9 sulle impostazioni.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/klang.io\/it\/help\/transcription-wizard\/\" \/>\n<meta property=\"og:site_name\" content=\"klang.io\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/klangio\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-01T06:18:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/retranscribe.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@klangio\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\/\/klang.io\/it\/help\/transcription-wizard\/\",\"url\":\"https:\/\/klang.io\/it\/help\/transcription-wizard\/\",\"name\":\"Come utilizzare la procedura guidata di Klangio Transcription | klang.io\",\"isPartOf\":{\"@id\":\"https:\/\/klang.io\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/klang.io\/it\/help\/transcription-wizard\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/klang.io\/it\/help\/transcription-wizard\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/retranscribe.png\",\"datePublished\":\"2024-09-09T14:12:02+00:00\",\"dateModified\":\"2025-12-01T06:18:47+00:00\",\"description\":\"La procedura guidata di Klangio Transcription rende la trascrizione musicale cos\u00ec facile che sembra magia! Leggi questa guida per saperne di pi\u00f9 sulle impostazioni.\",\"breadcrumb\":{\"@id\":\"https:\/\/klang.io\/it\/help\/transcription-wizard\/#breadcrumb\"},\"mainEntity\":[{\"@id\":\"https:\/\/klang.io\/it\/help\/transcription-wizard\/#faq-question-1764079700976\"}],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/klang.io\/it\/help\/transcription-wizard\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/klang.io\/it\/help\/transcription-wizard\/#primaryimage\",\"url\":\"https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/retranscribe.png\",\"contentUrl\":\"https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/retranscribe.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/klang.io\/it\/help\/transcription-wizard\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/klang.io\/it\/home-2\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Help Center\",\"item\":\"https:\/\/klang.io\/it\/help\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Come utilizzare la procedura guidata di Klangio Transcription\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/klang.io\/it\/#website\",\"url\":\"https:\/\/klang.io\/it\/\",\"name\":\"Klangio\",\"description\":\"AI Tools for Musicians\",\"publisher\":{\"@id\":\"https:\/\/klang.io\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/klang.io\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/klang.io\/it\/#organization\",\"name\":\"Klangio GmbH\",\"url\":\"https:\/\/klang.io\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/klang.io\/it\/#\/schema\/logo\/image\/\",\"url\":\"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png\",\"contentUrl\":\"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png\",\"width\":512,\"height\":512,\"caption\":\"Klangio GmbH\"},\"image\":{\"@id\":\"https:\/\/klang.io\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/klangio\",\"https:\/\/x.com\/klangio\",\"https:\/\/www.linkedin.com\/company\/klangio\/\",\"https:\/\/www.instagram.com\/klangio\/\",\"https:\/\/www.youtube.com\/@Klangio\"]},{\"@type\":\"Question\",\"@id\":\"https:\/\/klang.io\/it\/help\/transcription-wizard\/#faq-question-1764079700976\",\"position\":1,\"url\":\"https:\/\/klang.io\/it\/help\/transcription-wizard\/#faq-question-1764079700976\",\"name\":\"Klangio \u00e8 in grado di rilevare quali strumenti vengono suonati in una canzone o registrazione?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"S\u00ec. Nella procedura guidata di trascrizione, seleziona \\\"Rileva automaticamente gli strumenti\\\" dopo aver avviato una trascrizione. \",\"inLanguage\":\"it-IT\"},\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come utilizzare la procedura guidata di Klangio Transcription | klang.io","description":"La procedura guidata di Klangio Transcription rende la trascrizione musicale cos\u00ec facile che sembra magia! Leggi questa guida per saperne di pi\u00f9 sulle impostazioni.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/klang.io\/it\/help\/transcription-wizard\/","og_locale":"it_IT","og_type":"article","og_title":"Come utilizzare la procedura guidata di Klangio Transcription | klang.io","og_description":"La procedura guidata di Klangio Transcription rende la trascrizione musicale cos\u00ec facile che sembra magia! Leggi questa guida per saperne di pi\u00f9 sulle impostazioni.","og_url":"https:\/\/klang.io\/it\/help\/transcription-wizard\/","og_site_name":"klang.io","article_publisher":"https:\/\/facebook.com\/klangio","article_modified_time":"2025-12-01T06:18:47+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/retranscribe.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@klangio","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","FAQPage"],"@id":"https:\/\/klang.io\/it\/help\/transcription-wizard\/","url":"https:\/\/klang.io\/it\/help\/transcription-wizard\/","name":"Come utilizzare la procedura guidata di Klangio Transcription | klang.io","isPartOf":{"@id":"https:\/\/klang.io\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/klang.io\/it\/help\/transcription-wizard\/#primaryimage"},"image":{"@id":"https:\/\/klang.io\/it\/help\/transcription-wizard\/#primaryimage"},"thumbnailUrl":"https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/retranscribe.png","datePublished":"2024-09-09T14:12:02+00:00","dateModified":"2025-12-01T06:18:47+00:00","description":"La procedura guidata di Klangio Transcription rende la trascrizione musicale cos\u00ec facile che sembra magia! Leggi questa guida per saperne di pi\u00f9 sulle impostazioni.","breadcrumb":{"@id":"https:\/\/klang.io\/it\/help\/transcription-wizard\/#breadcrumb"},"mainEntity":[{"@id":"https:\/\/klang.io\/it\/help\/transcription-wizard\/#faq-question-1764079700976"}],"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/klang.io\/it\/help\/transcription-wizard\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/klang.io\/it\/help\/transcription-wizard\/#primaryimage","url":"https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/retranscribe.png","contentUrl":"https:\/\/klang.io\/wp-content\/uploads\/2024\/09\/retranscribe.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/klang.io\/it\/help\/transcription-wizard\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/klang.io\/it\/home-2\/"},{"@type":"ListItem","position":2,"name":"Help Center","item":"https:\/\/klang.io\/it\/help\/"},{"@type":"ListItem","position":3,"name":"Come utilizzare la procedura guidata di Klangio Transcription"}]},{"@type":"WebSite","@id":"https:\/\/klang.io\/it\/#website","url":"https:\/\/klang.io\/it\/","name":"Klangio","description":"AI Tools for Musicians","publisher":{"@id":"https:\/\/klang.io\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/klang.io\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/klang.io\/it\/#organization","name":"Klangio GmbH","url":"https:\/\/klang.io\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/klang.io\/it\/#\/schema\/logo\/image\/","url":"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png","contentUrl":"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png","width":512,"height":512,"caption":"Klangio GmbH"},"image":{"@id":"https:\/\/klang.io\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/klangio","https:\/\/x.com\/klangio","https:\/\/www.linkedin.com\/company\/klangio\/","https:\/\/www.instagram.com\/klangio\/","https:\/\/www.youtube.com\/@Klangio"]},{"@type":"Question","@id":"https:\/\/klang.io\/it\/help\/transcription-wizard\/#faq-question-1764079700976","position":1,"url":"https:\/\/klang.io\/it\/help\/transcription-wizard\/#faq-question-1764079700976","name":"Klangio \u00e8 in grado di rilevare quali strumenti vengono suonati in una canzone o registrazione?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"S\u00ec. Nella procedura guidata di trascrizione, seleziona \"Rileva automaticamente gli strumenti\" dopo aver avviato una trascrizione. ","inLanguage":"it-IT"},"inLanguage":"it-IT"}]}},"knowledge_base_info":[{"term_name":"Drum2Notes","term_url":"https:\/\/klang.io\/it\/help\/drum2notes-it\/","term_slug":"drum2notes-it"},{"term_name":"Guitar2Tabs","term_url":"https:\/\/klang.io\/it\/help\/guitar2tabs-it\/","term_slug":"guitar2tabs-it"},{"term_name":"Klangio Transcription Studio","term_url":"https:\/\/klang.io\/it\/help\/klangio-transcription-studio-it\/","term_slug":"klangio-transcription-studio-it"},{"term_name":"Piano2Notes","term_url":"https:\/\/klang.io\/it\/help\/piano2notes-it\/","term_slug":"piano2notes-it"},{"term_name":"Scan2Notes","term_url":"https:\/\/klang.io\/it\/help\/scan2notes-it\/","term_slug":"scan2notes-it"},{"term_name":"Sing2Notes","term_url":"https:\/\/klang.io\/it\/help\/sing2notes-it\/","term_slug":"sing2notes-it"}],"knowledge_base_slug":["drum2notes-it","guitar2tabs-it","klangio-transcription-studio-it","piano2notes-it","scan2notes-it","sing2notes-it"],"_links":{"self":[{"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/docs\/32380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/comments?post=32380"}],"version-history":[{"count":2,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/docs\/32380\/revisions"}],"predecessor-version":[{"id":41039,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/docs\/32380\/revisions\/41039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/media\/22667"}],"wp:attachment":[{"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/media?parent=32380"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/doc_category?post=32380"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/doc_tag?post=32380"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/knowledge_base?post=32380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}