{"id":32768,"date":"2024-04-03T14:02:44","date_gmt":"2024-04-03T14:02:44","guid":{"rendered":"https:\/\/klang.io\/help\/download-formats\/"},"modified":"2025-12-01T06:20:44","modified_gmt":"2025-12-01T06:20:44","password":"","slug":"download-formats","status":"publish","type":"docs","link":"https:\/\/klang.io\/it\/help\/download-formats\/","title":{"rendered":"Quali sono i diversi formati di Download\/Esportazione?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Se sei curioso di conoscere i diversi formati che puoi esportare dalla tua trascrizione <a href=\"https:\/\/klang.io\/it\/\">Klangio<\/a>, allora questo articolo fa proprio al caso tuo: chiariamo quali sono i diversi formati di download ed esportazione.<\/p>\n\n<p class=\"wp-block-paragraph\">Continua a leggere o guarda il video di YouTube:<\/p>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Different Download Formats of your Transcription | The Ultimate Guide to Klangio\" width=\"800\" height=\"450\" data-src=\"https:\/\/www.youtube.com\/embed\/HrSdbNbr03A?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe>\n<\/div><\/figure>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\">Dove Scarica una trascrizione<\/h2>\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-7387b849 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"635\" height=\"287\" src=\"\/wp-content\/uploads\/2024\/04\/grafik-6.png\" alt=\"\" class=\"wp-image-17473\" style=\"width:373px;height:auto\" srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-6.png 635w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-6-300x136.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-6-360x163.png 360w\" sizes=\"(max-width: 635px) 100vw, 635px\" \/><figcaption class=\"wp-element-caption\">Web: il pulsante di download nella colonna delle azioni del songbook<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"421\" height=\"241\" data-src=\"\/wp-content\/uploads\/2024\/06\/image.png\" alt=\"\" class=\"wp-image-20405 lazyload\" style=\"--smush-placeholder-width: 421px; --smush-placeholder-aspect-ratio: 421\/241;width:346px;height:auto\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/06\/image.png 421w, https:\/\/klang.io\/wp-content\/uploads\/2024\/06\/image-300x172.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/06\/image-360x206.png 360w\" data-sizes=\"(max-width: 421px) 100vw, 421px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">Mobile: apri una trascrizione e clicca sull&#8217;icona nell&#8217;angolo in alto a destra.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"375\" height=\"185\" data-src=\"\/wp-content\/uploads\/2024\/04\/image-19.png\" alt=\"Web: il pulsante di download nella parte superiore dello schermo nel visualizzatore di trascrizioni\" class=\"wp-image-23256 lazyload\" style=\"--smush-placeholder-width: 375px; --smush-placeholder-aspect-ratio: 375\/185;width:388px;height:auto\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/image-19.png 375w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/image-19-300x148.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/image-19-360x178.png 360w\" data-sizes=\"(max-width: 375px) 100vw, 375px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">Web: il pulsante di download nella parte superiore dello schermo nel visualizzatore di trascrizioni<\/figcaption><\/figure>\n<\/div>\n\n<p class=\"wp-block-paragraph\">Puoi scaricare una trascrizione direttamente nel <a href=\"\/?knowledge_base=songbook\" target=\"_blank\" rel=\"noreferrer noopener\">songbook<\/a>, passando con il mouse sopra il menu delle azioni della trascrizione, oppure cliccando sul pulsante di download nella parte superiore centrale del <a href=\"\/?knowledge_base=transcription-viewer\" target=\"_blank\" rel=\"noreferrer noopener\">visualizzatore di trascrizioni<\/a>. Tieni presente che alcuni formati di trascrizione sono disponibili solo con <a href=\"\/?knowledge_base=demo-to-full-transcription\" target=\"_blank\" rel=\"noreferrer noopener\">trascrizioni complete<\/a>. Inoltre, sentiti libero di provare la <a href=\"\/?knowledge_base=edit-mode\" target=\"_blank\" rel=\"noreferrer noopener\">Modalit\u00e0 di modifica<\/a> direttamente nel tuo browser, se stai cercando un modo rapido per apportare modifiche al tuo spartito.<\/p>\n\n<p class=\"wp-block-paragraph\">Diamo un&#8217;occhiata ai diversi formati di esportazione.<\/p>\n\n<h2 class=\"wp-block-heading\">Esporta PDF<\/h2>\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"933\" height=\"419\" data-src=\"\/wp-content\/uploads\/2024\/04\/grafik-8.png\" alt=\"Spartiti musicali di una trascrizione di Klangio Transcription esportati come file PDF.\" class=\"wp-image-17484 lazyload\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-8.png 933w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-8-300x135.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-8-768x345.png 768w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-8-360x162.png 360w\" data-sizes=\"(max-width: 933px) 100vw, 933px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 933px; --smush-placeholder-aspect-ratio: 933\/419;\" \/><figcaption class=\"wp-element-caption\">Un&#8217;esportazione PDF di una trascrizione<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Esportando un PDF, scaricherai un file che contiene lo spartito della trascrizione. Pu\u00f2 essere aperto con qualsiasi browser o lettore PDF come <g id=\"gid_0\">Adobe Reader<\/g>. Tieni presente che questi file non sono modificabili.  <\/p>\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"468\" height=\"250\" data-src=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/image-30.png\" alt=\"\" class=\"wp-image-38455 lazyload\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/image-30.png 468w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/image-30-300x160.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/image-30-360x192.png 360w\" data-sizes=\"(max-width: 468px) 100vw, 468px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 468px; --smush-placeholder-aspect-ratio: 468\/250;\" \/><figcaption class=\"wp-element-caption\">Klangio Transcription Studio: seleziona gli strumenti per i quali desideri esportare le note come PDF.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Tieni presente che se desideri esportare solo le note di un singolo strumento, quando hai trascritto pi\u00f9 strumenti con <a href=\"http:\/\/klang.io\/transcription-studio\" target=\"_blank\" rel=\"noreferrer noopener\">Klangio Transcription Studio<\/a>, puoi attivare o disattivare gli strumenti che desideri esportare prima di fare clic su &#8220;Download PDF&#8221; utilizzando il menu a tendina nell&#8217;angolo in alto a sinistra dello schermo<\/p>\n\n<h2 class=\"wp-block-heading\">Esporta MIDI e MIDI (unq.)<\/h2>\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"771\" height=\"250\" data-src=\"\/wp-content\/uploads\/2024\/03\/grafik-100.png\" alt=\"\" class=\"wp-image-17223 lazyload\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/grafik-100.png 771w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/grafik-100-300x97.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/grafik-100-768x249.png 768w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/grafik-100-360x117.png 360w\" data-sizes=\"(max-width: 771px) 100vw, 771px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 771px; --smush-placeholder-aspect-ratio: 771\/250;\" \/><figcaption class=\"wp-element-caption\">Un file MIDI aperto in un Pianoroll di una DAW (Digital Audio Workstation)<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Uno dei modi pi\u00f9 comuni per archiviare la musica come note \u00e8 in un formato chiamato <a href=\"https:\/\/de.wikipedia.org\/wiki\/MIDI\" target=\"_blank\" rel=\"noreferrer noopener\">MIDI<\/a>, che viene comunemente utilizzato per la produzione musicale. Dopo aver scaricato un file MIDI, puoi <a href=\"\/?knowledge_base=open-midi\" target=\"_blank\" rel=\"noreferrer noopener\">aprirlo in una Digital Audio Workstation per modificarlo<\/a>. Tieni presente che <a href=\"\/?knowledge_base=quantized-unquantized-midi-difference\" target=\"_blank\" rel=\"noreferrer noopener\">MIDI e MIDI non quantizzati presentano lievi differenze<\/a>.<\/p>\n\n<h2 class=\"wp-block-heading\">Esporta MusicXML<\/h2>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"932\" height=\"643\" data-src=\"\/wp-content\/uploads\/2024\/03\/grafik-120.png\" alt=\"Una trascrizione da Klangio, esportata come MusicXML e aperta in Sibelius.\" class=\"wp-image-17423 lazyload\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/grafik-120.png 932w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/grafik-120-300x207.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/grafik-120-768x530.png 768w, https:\/\/klang.io\/wp-content\/uploads\/2024\/03\/grafik-120-360x248.png 360w\" data-sizes=\"(max-width: 932px) 100vw, 932px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 932px; --smush-placeholder-aspect-ratio: 932\/643;\" \/><figcaption class=\"wp-element-caption\">Un&#8217;esportazione MusicXML aperta in Sibelius.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">MusicXML \u00e8 come un mix di MIDI e uno spartito PDF: \u00e8 una notazione modificabile come MIDI, ma formattata come spartito. Puoi <a href=\"\/?knowledge_base=open-musicxml\" target=\"_blank\" rel=\"noreferrer noopener\">aprire questi file con editor di composizione musicale come MuseScore, Sibelius e Finale<\/a>.  Proprio come con l&#8217;esportazione MIDI quantizzata, il file MusicXML non si adatta alle variazioni di tempo dell&#8217;audio originale e utilizza invece il tempo nominale rilevato nel file audio.<\/p>\n\n<h2 class=\"wp-block-heading\">Esporta LilyPond<\/h2>\n\n<p class=\"wp-block-paragraph\">LilyPond \u00e8 un programma di incisione musicale che produce spartiti di alta qualit\u00e0 da input basati su testo. \u00c8 un po&#8217; come LaTeX ma per la notazione musicale, permettendoti di scrivere musica in un formato di testo semplice, che LilyPond elabora poi per generare spartiti splendidamente formattati. Con le app Klangio, puoi importare questo formato in LilyPond.  <\/p>\n\n<h2 class=\"wp-block-heading\">Esporta GP5<\/h2>\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img decoding=\"async\" width=\"1024\" height=\"491\" data-src=\"\/wp-content\/uploads\/2024\/04\/grafik-9-1024x491.png\" alt=\"Una trascrizione di Klangio Transcription, esportata come file Guitar Pro e aperta in TuxGuitar.\" class=\"wp-image-17489 lazyload\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/491;width:645px;height:auto\" data-srcset=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-9-1024x491.png 1024w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-9-300x144.png 300w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-9-768x368.png 768w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-9-360x172.png 360w, https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/grafik-9.png 1144w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><figcaption class=\"wp-element-caption\">Un&#8217;esportazione GP5 aperta in TuxGuitar<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Per <a href=\"https:\/\/klang.io\/it\/guitar2tabs\/\">Guitar2Tabs<\/a>, esiste un formato di download esclusivo: un file Guitar Pro. Questi sono abbastanza simili a MusicXML, ma si concentrano sulla visualizzazione della tablatura per chitarra invece dello spartito. <a href=\"\/?knowledge_base=open-guitarpro\" target=\"_blank\" rel=\"noreferrer noopener\">Possono essere aperti con Guitar Pro Editor o TuxGuitar<\/a>.<\/p>\n\n<p class=\"wp-block-paragraph\">Sentiti libero di consultare gli altri articoli nel nostro <a href=\"https:\/\/klang.io\/help\">Centro Aiuto<\/a>, se hai domande sui diversi formati di download ed esportazione di Klangio.<\/p>\n\n<h2 class=\"wp-block-heading\">Domande frequenti<\/h2>\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1764079860548\"><strong class=\"schema-faq-question\">Il mio download non si avvia.<\/strong> <p class=\"schema-faq-answer\">I fogli di grandi dimensioni potrebbero richiedere alcuni minuti prima che inizi il download.<br\/>Si prega di attendere un po&#8217; dopo aver selezionato il formato di esportazione.<br\/>Se il download ancora non si avvia, non esitare a contattarci in modo che possiamo indagare.<\/p> <\/div> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Se sei curioso di conoscere i diversi formati che puoi esportare dalla tua trascrizione Klangio, allora questo articolo fa proprio al caso tuo: chiariamo quali sono i diversi formati di download ed esportazione. Continua a leggere o guarda il video di YouTube: Dove Scarica una trascrizione Puoi scaricare una trascrizione direttamente nel songbook, passando con [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":17500,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"doc_category":[534],"doc_tag":[],"knowledge_base":[467,465,468,497,464,469,466],"class_list":["post-32768","docs","type-docs","status-publish","has-post-thumbnail","hentry","doc_category-esportazione-delle-trascrizioni","knowledge_base-drum2notes-it","knowledge_base-guitar2tabs-it","knowledge_base-klangio-transcription-studio-it","knowledge_base-melody-scanner-it","knowledge_base-piano2notes-it","knowledge_base-scan2notes-it","knowledge_base-sing2notes-it"],"year_month":"2026-07","word_count":583,"total_views":"697","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"Christoph Zimmer","author_nicename":"chris","author_url":"https:\/\/klang.io\/it\/blog\/author\/chris\/"},"doc_category_info":[{"term_name":"Esportazione delle trascrizioni","term_url":"https:\/\/klang.io\/it\/help\/non-knowledgebase\/esportazione-delle-trascrizioni\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quali sono i diversi formati di Download\/Esportazione? | klang.io<\/title>\n<meta name=\"description\" content=\"Scopri le differenze tra i formati di Download\/Esportazione disponibili per le trascrizioni delle app Klangio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/klang.io\/it\/help\/download-formats\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quali sono i diversi formati di Download\/Esportazione? | klang.io\" \/>\n<meta property=\"og:description\" content=\"Scopri le differenze tra i formati di Download\/Esportazione disponibili per le trascrizioni delle app Klangio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/klang.io\/it\/help\/download-formats\/\" \/>\n<meta property=\"og:site_name\" content=\"klang.io\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/klangio\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-01T06:20:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/download-formats.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@klangio\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\/\/klang.io\/it\/help\/download-formats\/\",\"url\":\"https:\/\/klang.io\/it\/help\/download-formats\/\",\"name\":\"Quali sono i diversi formati di Download\/Esportazione? | klang.io\",\"isPartOf\":{\"@id\":\"https:\/\/klang.io\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/klang.io\/it\/help\/download-formats\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/klang.io\/it\/help\/download-formats\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/download-formats.png\",\"datePublished\":\"2024-04-03T14:02:44+00:00\",\"dateModified\":\"2025-12-01T06:20:44+00:00\",\"description\":\"Scopri le differenze tra i formati di Download\/Esportazione disponibili per le trascrizioni delle app Klangio.\",\"breadcrumb\":{\"@id\":\"https:\/\/klang.io\/it\/help\/download-formats\/#breadcrumb\"},\"mainEntity\":[{\"@id\":\"https:\/\/klang.io\/it\/help\/download-formats\/#faq-question-1764079860548\"}],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/klang.io\/it\/help\/download-formats\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/klang.io\/it\/help\/download-formats\/#primaryimage\",\"url\":\"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/download-formats.png\",\"contentUrl\":\"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/download-formats.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/klang.io\/it\/help\/download-formats\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/klang.io\/it\/home-2\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Help Center\",\"item\":\"https:\/\/klang.io\/it\/help\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Quali sono i diversi formati di Download\/Esportazione?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/klang.io\/it\/#website\",\"url\":\"https:\/\/klang.io\/it\/\",\"name\":\"Klangio\",\"description\":\"AI Tools for Musicians\",\"publisher\":{\"@id\":\"https:\/\/klang.io\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/klang.io\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/klang.io\/it\/#organization\",\"name\":\"Klangio GmbH\",\"url\":\"https:\/\/klang.io\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/klang.io\/it\/#\/schema\/logo\/image\/\",\"url\":\"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png\",\"contentUrl\":\"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png\",\"width\":512,\"height\":512,\"caption\":\"Klangio GmbH\"},\"image\":{\"@id\":\"https:\/\/klang.io\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/klangio\",\"https:\/\/x.com\/klangio\",\"https:\/\/www.linkedin.com\/company\/klangio\/\",\"https:\/\/www.instagram.com\/klangio\/\",\"https:\/\/www.youtube.com\/@Klangio\"]},{\"@type\":\"Question\",\"@id\":\"https:\/\/klang.io\/it\/help\/download-formats\/#faq-question-1764079860548\",\"position\":1,\"url\":\"https:\/\/klang.io\/it\/help\/download-formats\/#faq-question-1764079860548\",\"name\":\"Il mio download non si avvia.\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"I fogli di grandi dimensioni potrebbero richiedere alcuni minuti prima che inizi il download.<br>Si prega di attendere un po' dopo aver selezionato il formato di esportazione.<br>Se il download ancora non si avvia, non esitare a contattarci in modo che possiamo indagare.\",\"inLanguage\":\"it-IT\"},\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quali sono i diversi formati di Download\/Esportazione? | klang.io","description":"Scopri le differenze tra i formati di Download\/Esportazione disponibili per le trascrizioni delle app Klangio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/klang.io\/it\/help\/download-formats\/","og_locale":"it_IT","og_type":"article","og_title":"Quali sono i diversi formati di Download\/Esportazione? | klang.io","og_description":"Scopri le differenze tra i formati di Download\/Esportazione disponibili per le trascrizioni delle app Klangio.","og_url":"https:\/\/klang.io\/it\/help\/download-formats\/","og_site_name":"klang.io","article_publisher":"https:\/\/facebook.com\/klangio","article_modified_time":"2025-12-01T06:20:44+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/download-formats.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@klangio","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","FAQPage"],"@id":"https:\/\/klang.io\/it\/help\/download-formats\/","url":"https:\/\/klang.io\/it\/help\/download-formats\/","name":"Quali sono i diversi formati di Download\/Esportazione? | klang.io","isPartOf":{"@id":"https:\/\/klang.io\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/klang.io\/it\/help\/download-formats\/#primaryimage"},"image":{"@id":"https:\/\/klang.io\/it\/help\/download-formats\/#primaryimage"},"thumbnailUrl":"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/download-formats.png","datePublished":"2024-04-03T14:02:44+00:00","dateModified":"2025-12-01T06:20:44+00:00","description":"Scopri le differenze tra i formati di Download\/Esportazione disponibili per le trascrizioni delle app Klangio.","breadcrumb":{"@id":"https:\/\/klang.io\/it\/help\/download-formats\/#breadcrumb"},"mainEntity":[{"@id":"https:\/\/klang.io\/it\/help\/download-formats\/#faq-question-1764079860548"}],"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/klang.io\/it\/help\/download-formats\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/klang.io\/it\/help\/download-formats\/#primaryimage","url":"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/download-formats.png","contentUrl":"https:\/\/klang.io\/wp-content\/uploads\/2024\/04\/download-formats.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/klang.io\/it\/help\/download-formats\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/klang.io\/it\/home-2\/"},{"@type":"ListItem","position":2,"name":"Help Center","item":"https:\/\/klang.io\/it\/help\/"},{"@type":"ListItem","position":3,"name":"Quali sono i diversi formati di Download\/Esportazione?"}]},{"@type":"WebSite","@id":"https:\/\/klang.io\/it\/#website","url":"https:\/\/klang.io\/it\/","name":"Klangio","description":"AI Tools for Musicians","publisher":{"@id":"https:\/\/klang.io\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/klang.io\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/klang.io\/it\/#organization","name":"Klangio GmbH","url":"https:\/\/klang.io\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/klang.io\/it\/#\/schema\/logo\/image\/","url":"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png","contentUrl":"\/wp-content\/uploads\/2021\/12\/cropped-Klangio-Logo-icon-1C.png","width":512,"height":512,"caption":"Klangio GmbH"},"image":{"@id":"https:\/\/klang.io\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/klangio","https:\/\/x.com\/klangio","https:\/\/www.linkedin.com\/company\/klangio\/","https:\/\/www.instagram.com\/klangio\/","https:\/\/www.youtube.com\/@Klangio"]},{"@type":"Question","@id":"https:\/\/klang.io\/it\/help\/download-formats\/#faq-question-1764079860548","position":1,"url":"https:\/\/klang.io\/it\/help\/download-formats\/#faq-question-1764079860548","name":"Il mio download non si avvia.","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"I fogli di grandi dimensioni potrebbero richiedere alcuni minuti prima che inizi il download.<br>Si prega di attendere un po' dopo aver selezionato il formato di esportazione.<br>Se il download ancora non si avvia, non esitare a contattarci in modo che possiamo indagare.","inLanguage":"it-IT"},"inLanguage":"it-IT"}]}},"knowledge_base_info":[{"term_name":"Drum2Notes","term_url":"https:\/\/klang.io\/it\/help\/drum2notes-it\/","term_slug":"drum2notes-it"},{"term_name":"Guitar2Tabs","term_url":"https:\/\/klang.io\/it\/help\/guitar2tabs-it\/","term_slug":"guitar2tabs-it"},{"term_name":"Klangio Transcription Studio","term_url":"https:\/\/klang.io\/it\/help\/klangio-transcription-studio-it\/","term_slug":"klangio-transcription-studio-it"},{"term_name":"Melody Scanner","term_url":"https:\/\/klang.io\/it\/help\/melody-scanner-it\/","term_slug":"melody-scanner-it"},{"term_name":"Piano2Notes","term_url":"https:\/\/klang.io\/it\/help\/piano2notes-it\/","term_slug":"piano2notes-it"},{"term_name":"Scan2Notes","term_url":"https:\/\/klang.io\/it\/help\/scan2notes-it\/","term_slug":"scan2notes-it"},{"term_name":"Sing2Notes","term_url":"https:\/\/klang.io\/it\/help\/sing2notes-it\/","term_slug":"sing2notes-it"}],"knowledge_base_slug":["drum2notes-it","guitar2tabs-it","klangio-transcription-studio-it","melody-scanner-it","piano2notes-it","scan2notes-it","sing2notes-it"],"_links":{"self":[{"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/docs\/32768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/comments?post=32768"}],"version-history":[{"count":4,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/docs\/32768\/revisions"}],"predecessor-version":[{"id":41107,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/docs\/32768\/revisions\/41107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/media\/17500"}],"wp:attachment":[{"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/media?parent=32768"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/doc_category?post=32768"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/doc_tag?post=32768"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/klang.io\/it\/wp-json\/wp\/v2\/knowledge_base?post=32768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}